{"id":901,"count":1,"description":"","link":"https:\/\/a-igeco.fr\/en\/recherche-centre\/cnrs-terre-univers-directeur\/","name":"CNRS Terre &amp; Univers. Directeur","slug":"cnrs-terre-univers-directeur","taxonomy":"recherche_centre","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des CNRS Terre &amp; Univers. Directeur - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/recherche-centre\/cnrs-terre-univers-directeur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des CNRS Terre &amp; Univers. Directeur - A-Igeco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/recherche-centre\/cnrs-terre-univers-directeur\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/recherche-centre\\\/cnrs-terre-univers-directeur\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/recherche-centre\\\/cnrs-terre-univers-directeur\\\/\",\"name\":\"Archives des CNRS Terre &amp; Univers. Directeur - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/recherche-centre\\\/cnrs-terre-univers-directeur\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/recherche-centre\\\/cnrs-terre-univers-directeur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CNRS Terre &amp; Univers. Directeur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des CNRS Terre &amp; Univers. Directeur - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/recherche-centre\/cnrs-terre-univers-directeur\/","og_locale":"en_US","og_type":"article","og_title":"Archives des CNRS Terre &amp; Univers. Directeur - A-Igeco","og_url":"https:\/\/a-igeco.fr\/recherche-centre\/cnrs-terre-univers-directeur\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/a-igeco.fr\/recherche-centre\/cnrs-terre-univers-directeur\/","url":"https:\/\/a-igeco.fr\/recherche-centre\/cnrs-terre-univers-directeur\/","name":"Archives des CNRS Terre &amp; Univers. Directeur - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"breadcrumb":{"@id":"https:\/\/a-igeco.fr\/recherche-centre\/cnrs-terre-univers-directeur\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/recherche-centre\/cnrs-terre-univers-directeur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"CNRS Terre &amp; Univers. Directeur"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre\/901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/taxonomies\/recherche_centre"}],"wp:post_type":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur?recherche_centre=901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}