{"id":1170,"date":"2026-02-12T14:45:35","date_gmt":"2026-02-12T13:45:35","guid":{"rendered":"https:\/\/a-igeco.fr\/?p=1170"},"modified":"2026-07-07T19:06:23","modified_gmt":"2026-07-07T17:06:23","slug":"le-projet-isere-amont-un-projet-gema-avant-lheure","status":"publish","type":"post","link":"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/","title":{"rendered":"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure !"},"content":{"rendered":"\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-3749991f wp-block-group-is-layout-constrained\">\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-box-title\">Sommaire<\/div>\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Laureat_du_Grand_Prix\" >Laur\u00e9at du Grand Prix<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Un_projet_realise_par_porteur_projet_partenaires_techniques_et_financiers\" >Un projet r\u00e9alis\u00e9 par (porteur projet, partenaires techniques et financiers) :<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Presentation_synthetique_du_projet\" >Pr\u00e9sentation synth\u00e9tique du projet<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Les_objectifs_du_projet\" >Les objectifs du projet&nbsp;:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Quelques_chiffres\" >Quelques chiffres :<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Cout\" >Co\u00fbt<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Site_internet_et_page_web_lie_au_projet\" >Site internet et page web li\u00e9 au projet :<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Autres_projets_qui_peuvent_vous_interesser\" >Autres projets qui peuvent vous int\u00e9resser<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Le_projet_ISERE_AMONT_un_projet_GEMA_avant_lheure\" >Le projet ISERE AMONT, un projet GEMA avant l\u2019heure !<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Chantier-ecole_dans_le_cadre_du_projet_PROTEGER_%E2%80%93_Phase_2\" >Chantier-\u00e9cole dans le cadre du projet PROT\u00c9GER \u2013 Phase 2<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Programme_REEVES_Recherche_sur_les_Especes_Exotiques_Vegetales_EnvahissanteS\" >Programme REEVES (Recherche sur les Esp\u00e8ces Exotiques V\u00e9g\u00e9tales EnvahissanteS)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Le_Parc_Jardin_de_la_Sente_des_Rivieres_Un_amenagement_exemplaire_pour_la_preservation_de_la_biodiversite\" >Le Parc Jardin de la Sente des Rivi\u00e8res : Un am\u00e9nagement exemplaire pour la pr\u00e9servation de la biodiversit\u00e9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Travaux_de_protection_contre_les_crues_et_de_restauration_environnementale_de_la_riviere_Yzeron_en_zone_urbaine_a_Sainte_Foy-les-Lyon_Rhone\" >Travaux de protection contre les crues et de restauration environnementale de la rivi\u00e8re Yzeron en zone urbaine \u00e0 Sainte Foy-l\u00e8s-Lyon (Rh\u00f4ne)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Projet_integre_de_restauration_des_milieux_naturels_de_La_Reunion\" >Projet int\u00e9gr\u00e9 de restauration des milieux naturels de La R\u00e9union<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Restauration_de_la_continuite_ecologique_et_de_lhydromorphologie_du_ruisseau_de_la_Vitardiere_76\" >Restauration de la continuit\u00e9 \u00e9cologique et de l\u2019hydromorphologie du ruisseau de la Vitardi\u00e8re (76)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Restauration_des_fonctionnalites_ecologiques_de_la_Nivelle_a_Ainhoa_64\" >Restauration des fonctionnalit\u00e9s \u00e9cologiques de la Nivelle \u00e0 Ainhoa (64)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#Restauration_du_marais_de_Panesiere\" >Restauration du marais de Panesiere<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h3 class=\"wp-block-heading\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:0\"><span class=\"ez-toc-section\" id=\"Laureat_du_Grand_Prix\"><\/span>Laur\u00e9at du Grand Prix<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/8v5qLjtnCBc?si=QMKs8zKA_Ea0oajp\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"margin-top:var(--wp--preset--spacing--60);margin-bottom:0\"><span class=\"ez-toc-section\" id=\"Un_projet_realise_par_porteur_projet_partenaires_techniques_et_financiers\"><\/span>Un projet r\u00e9alis\u00e9 par (porteur projet, partenaires techniques et financiers) :<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\" style=\"margin-top:var(--wp--preset--spacing--50);margin-bottom:var(--wp--preset--spacing--50)\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"257\" src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure-.png\" alt=\"\" class=\"wp-image-1173\" srcset=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure-.png 512w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure--300x151.png 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Le SYMBHI (Syndicat Mixte des Bassins Hydrauliques de l\u2019Is\u00e8re) est gestionnaire de la comp\u00e9tence GEMAPI sur le bassin versant de l\u2019Is\u00e8re. Il assure deux principaux objectifs&nbsp;:<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Prot\u00e9ger les personnes et les biens contre les inondations.<\/em><\/li>\n\n\n\n<li><em>Pr\u00e9server, restaurer et mettre en valeur la rivi\u00e8re et les milieux aquatiques associ\u00e9s.<\/em><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"margin-top:var(--wp--preset--spacing--60)\"><span class=\"ez-toc-section\" id=\"Presentation_synthetique_du_projet\"><\/span>Pr\u00e9sentation synth\u00e9tique du projet<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">CLe projet Is\u00e8re Amont est un projet de pr\u00e9vention du risque inondation bas\u00e9 sur des solutions fond\u00e9es sur la nature datant de 2004. Il s\u2019inscrit dans un contexte d\u2019endiguement de l\u2019Is\u00e8re g\u00e9n\u00e9ralis\u00e9 tout le long de la vall\u00e9e du Gr\u00e9sivaudan depuis le XVIII\u00e8me si\u00e8cle. Il repose sur un changement de paradigme de la pr\u00e9vention du risque inondation en redonnant de la place \u00e0 la rivi\u00e8re pour \u00e9tendre ses crues dans la plaine alluviale.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\" style=\"margin-top:var(--wp--preset--spacing--50);margin-bottom:var(--wp--preset--spacing--50)\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"258\" src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/2-Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure-.jpg\" alt=\"\" class=\"wp-image-1174\" style=\"width:645px;height:auto\" srcset=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/2-Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure-.jpg 512w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/2-Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure--300x151.jpg 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"margin-top:var(--wp--preset--spacing--60)\"><span class=\"ez-toc-section\" id=\"Les_objectifs_du_projet\"><\/span>Les objectifs du projet&nbsp;:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cr\u00e9ation d\u2019espaces de loisirs, de circuits d\u00e9di\u00e9s aux mobilit\u00e9s douces et des haltes vertes sur les digues et anciennes digues de l\u2019Is\u00e8re.<\/li>\n\n\n\n<li>Niveau de protection des zones \u00e0 enjeux contre la crue bi-centennale (Q200) ;<\/li>\n\n\n\n<li>Mise en \u0153uvre de solutions fond\u00e9es sur la nature pour la protection contre les inondations gr\u00e2ce \u00e0 des Champ d\u2019inondations contr\u00f4l\u00e9s (CIC) ;<\/li>\n\n\n\n<li>Reconnexion piscicole de 7 affluents \u00e0 l\u2019Is\u00e8re et le renforcement du corridor bois\u00e9 le long de l\u2019Is\u00e8re ;<\/li>\n\n\n\n<li>Redynamisation et recr\u00e9ation d\u2019annexes hydrauliques pour cr\u00e9er une mosa\u00efque d\u2019habitats int\u00e9ressants pour des esp\u00e8ces patrimoniales ;<\/li>\n\n\n\n<li>Effacement de digues entre l\u2019Is\u00e8re, les for\u00eats alluviales et certaines gravi\u00e8res pour les reconnecter \u00e0 hautes eaux;<\/li>\n\n\n\n<li>Cr\u00e9ation d\u2019espaces de loisirs, de circuits d\u00e9di\u00e9s aux mobilit\u00e9s douces et des haltes vertes sur les digues et anciennes digues de l\u2019Is\u00e8re.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\" style=\"margin-top:var(--wp--preset--spacing--50);margin-bottom:var(--wp--preset--spacing--50)\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"431\" src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/3-Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure-.jpg\" alt=\"\" class=\"wp-image-1175\" style=\"width:624px;height:auto\" srcset=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/3-Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure-.jpg 512w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/3-Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure--300x253.jpg 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull bloc-vert has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#0f664a;margin-top:var(--wp--preset--spacing--50);margin-bottom:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--70);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--70)\">\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-base-color has-text-color has-link-color wp-elements-8d45ea129f77a78d58d4e2784865ec85\"><span class=\"ez-toc-section\" id=\"Quelques_chiffres\"><\/span>Quelques chiffres :<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<ul class=\"wp-block-list has-base-color has-text-color has-link-color wp-elements-ef3443c1f6bd65a019c51ea0dd8184e7\">\n<li>29 communes sont concern\u00e9es par le projet<\/li>\n\n\n\n<li>Cela concerne 300 000 habitants sur le territoire<\/li>\n\n\n\n<li>16 champs d\u2019inondations contr\u00f4l\u00e9es (CIC) ont \u00e9t\u00e9 am\u00e9nag\u00e9s, correspondant \u00e0 3 500 hectares*<\/li>\n\n\n\n<li>Ces CIC ont une capacit\u00e9 de stockage de 35 millions de m3 d\u2019eau de crue.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-528ab1a8 wp-block-columns-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--70)\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--60)\">\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cout\"><\/span>Co\u00fbt<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le projet Is\u00e8re Amont repr\u00e9sente 135 M\u20ac HT d\u2019investissement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Voir le diaporama de pr\u00e9sentation en cliquant sur le bouton ci-dessous<\/em><\/p>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-8b6614bd\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-b465c63d wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/symbhi.fr\/nos-territoires\/le-gresivaudan\/isere-amont\/\" rel=\"follow noopener\" target=\"_blank\" role=\"button\"><div class=\"uagb-button__link\">Diaporama<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 320 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M318.4 304.5c-3.531 9.344-12.47 15.52-22.45 15.52h-105l45.15 94.82c9.496 19.94 1.031 43.8-18.91 53.31c-19.95 9.504-43.82 1.035-53.32-18.91L117.3 351.3l-75 88.25c-4.641 5.469-11.37 8.453-18.28 8.453c-2.781 0-5.578-.4844-8.281-1.469C6.281 443.1 0 434.1 0 423.1V56.02c0-9.438 5.531-18.03 14.12-21.91C22.75 30.26 32.83 31.77 39.87 37.99l271.1 240C319.4 284.6 321.1 295.1 318.4 304.5z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\" style=\"margin-top:var(--wp--preset--spacing--50);margin-bottom:var(--wp--preset--spacing--50)\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"335\" src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/4-Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure-.jpg\" alt=\"\" class=\"wp-image-1176\" srcset=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/4-Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure-.jpg 512w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/4-Le-projet-ISERE-AMONT-un-projet-GEMA-avant-lheure--300x196.jpg 300w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-3749991f wp-block-group-is-layout-constrained\"><p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/4zXxZeJz95Q?si=cknyqo1sSgfUsWJX\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"margin-top:var(--wp--preset--spacing--60)\"><span class=\"ez-toc-section\" id=\"Site_internet_et_page_web_lie_au_projet\"><\/span>Site internet et page web li\u00e9 au projet :<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-b717f317\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-3af76666 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/symbhi.fr\/nos-territoires\/le-gresivaudan\/isere-amont\/\" rel=\"follow noopener\" target=\"_blank\" role=\"button\"><div class=\"uagb-button__link\">symbhi.fr\/nos-territoires\/le-gresivaudan\/isere-amont\/<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 320 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M318.4 304.5c-3.531 9.344-12.47 15.52-22.45 15.52h-105l45.15 94.82c9.496 19.94 1.031 43.8-18.91 53.31c-19.95 9.504-43.82 1.035-53.32-18.91L117.3 351.3l-75 88.25c-4.641 5.469-11.37 8.453-18.28 8.453c-2.781 0-5.578-.4844-8.281-1.469C6.281 443.1 0 434.1 0 423.1V56.02c0-9.438 5.531-18.03 14.12-21.91C22.75 30.26 32.83 31.77 39.87 37.99l271.1 240C319.4 284.6 321.1 295.1 318.4 304.5z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-1731824d wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-left has-text-color has-link-color has-figtree-font-family wp-elements-fb23f4dfed5495115e8cb4ead384f96a\" style=\"color:#0f664a;margin-top:var(--wp--preset--spacing--80);margin-left:0;font-size:clamp(24.034px, 1.502rem + ((1vw - 3.2px) * 1.565), 40px);font-style:normal;font-weight:600\"><span class=\"ez-toc-section\" id=\"Autres_projets_qui_peuvent_vous_interesser\"><\/span>Autres projets qui peuvent vous int\u00e9resser<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n    <div class=\"zfc-wrapper\" id=\"zfc-6a57820e3bb92\" data-per-page=\"3\">\n\n        \n        <div class=\"zfc-track-wrapper\">\n            <div class=\"zfc-track\">\n                                    <div class=\"zfc-card\">\n                                                    <a href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/\" class=\"zfc-card-link\" aria-label=\"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure !\">\n                        \n                            <div class=\"zfc-card-image\">\n                                                                    <img decoding=\"async\"\n                                        src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Laureat-Grand-prix-PGE-2024-Projet-amenagement-integre-Isere-Amont.png\"\n                                        alt=\"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure !\"\n                                        loading=\"lazy\"\n                                    \/>\n                                                            <\/div>\n\n                            <div class=\"zfc-card-body\">\n                                                                    <span class=\"zfc-card-cat\">projets laur\u00e9ats<\/span>\n                                                                <h3 class=\"zfc-card-title\"><span class=\"ez-toc-section\" id=\"Le_projet_ISERE_AMONT_un_projet_GEMA_avant_lheure\"><\/span>Le projet ISERE AMONT, un projet GEMA avant l\u2019heure !<span class=\"ez-toc-section-end\"><\/span><\/h3>\n                                                                    <p class=\"zfc-card-desc\">Laur\u00e9at du Grand Prix Un projet r\u00e9alis\u00e9 par (porteur projet, partenaires techniques et financiers) : Le SYMBHI (Syndicat Mixte des Bassins Hydrauliques de l\u2019Is\u00e8re) est gestionnaire de la comp\u00e9tence GEMAPI sur le bassin versant de l\u2019Is\u00e8re. Il assure deux principaux objectifs&nbsp;: Pr\u00e9sentation synth\u00e9tique du projet CLe projet Is\u00e8re Amont est un projet de pr\u00e9vention du [&hellip;]<\/p>\n                                                            <\/div>\n\n                                                    <\/a>\n                                            <\/div>\n                                    <div class=\"zfc-card\">\n                                                    <a href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/chantier-ecole-dans-le-cadre-du-projet-proteger-phase-2\/\" class=\"zfc-card-link\" aria-label=\"Chantier-\u00e9cole dans le cadre du projet PROT\u00c9GER \u2013 Phase 2\">\n                        \n                            <div class=\"zfc-card-image\">\n                                                                    <img decoding=\"async\"\n                                        src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Laureat-prix-special-jury-PGE-2024-Chantier-ecole-PROTEGER-Phase2.png\"\n                                        alt=\"Chantier-\u00e9cole dans le cadre du projet PROT\u00c9GER \u2013 Phase 2\"\n                                        loading=\"lazy\"\n                                    \/>\n                                                            <\/div>\n\n                            <div class=\"zfc-card-body\">\n                                                                    <span class=\"zfc-card-cat\">projets laur\u00e9ats<\/span>\n                                                                <h3 class=\"zfc-card-title\"><span class=\"ez-toc-section\" id=\"Chantier-ecole_dans_le_cadre_du_projet_PROTEGER_%E2%80%93_Phase_2\"><\/span>Chantier-\u00e9cole dans le cadre du projet PROT\u00c9GER \u2013 Phase 2<span class=\"ez-toc-section-end\"><\/span><\/h3>\n                                                                    <p class=\"zfc-card-desc\">Laur\u00e9at du Prix Sp\u00e9cial du Jury Un projet r\u00e9alis\u00e9 par (porteur projet, partenaires techniques et financiers) : Pr\u00e9sentation synth\u00e9tique du projet Le Parc National de la Guadeloupe s\u2019est engag\u00e9 dans le projet PROT\u00c9GER* pour agir sur une des causes de l\u2019\u00e9rosion des populations de poissons et crustac\u00e9s des habitats en milieux d\u2019eaux douces : l\u2019artificialisation [&hellip;]<\/p>\n                                                            <\/div>\n\n                                                    <\/a>\n                                            <\/div>\n                                    <div class=\"zfc-card\">\n                                                    <a href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/programme-reeves-recherche-sur-les-especes-exotiques-vegetales-envahissantes\/\" class=\"zfc-card-link\" aria-label=\"Programme REEVES (Recherche sur les Esp\u00e8ces Exotiques V\u00e9g\u00e9tales EnvahissanteS)\">\n                        \n                            <div class=\"zfc-card-image\">\n                                                                    <img decoding=\"async\"\n                                        src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Laureat-cat.experimentation-PGE-2024-Programme-REEVES-SNCF-Reseau.png\"\n                                        alt=\"Programme REEVES (Recherche sur les Esp\u00e8ces Exotiques V\u00e9g\u00e9tales EnvahissanteS)\"\n                                        loading=\"lazy\"\n                                    \/>\n                                                            <\/div>\n\n                            <div class=\"zfc-card-body\">\n                                                                    <span class=\"zfc-card-cat\">projets laur\u00e9ats<\/span>\n                                                                <h3 class=\"zfc-card-title\"><span class=\"ez-toc-section\" id=\"Programme_REEVES_Recherche_sur_les_Especes_Exotiques_Vegetales_EnvahissanteS\"><\/span>Programme REEVES (Recherche sur les Esp\u00e8ces Exotiques V\u00e9g\u00e9tales EnvahissanteS)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n                                                                    <p class=\"zfc-card-desc\">Laur\u00e9at du Prix \u201cExp\u00e9rimentation et recherche appliqu\u00e9e\u201d Un projet r\u00e9alis\u00e9 par (porteur du projet et partenaires scientifiques) : Pr\u00e9sentation synth\u00e9tique du projet Le R\u00e9seau Ferr\u00e9 National (RFN) et le gestionnaire d\u2019infrastructure (SNCF R\u00e9seau) font face \u00e0 la propagation de plusieurs esp\u00e8ces v\u00e9g\u00e9tales class\u00e9es comme des plantes exotiques envahissantes. L\u2019entretien de la v\u00e9g\u00e9tation aux abords des [&hellip;]<\/p>\n                                                            <\/div>\n\n                                                    <\/a>\n                                            <\/div>\n                                    <div class=\"zfc-card\">\n                                                    <a href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/le-parc-jardin-de-la-sente-des-rivieres-un-amenagement-exemplaire-pour-la-preservation-de-la-biodiversite\/\" class=\"zfc-card-link\" aria-label=\"Le Parc Jardin de la Sente des Rivi\u00e8res : Un am\u00e9nagement exemplaire pour la pr\u00e9servation de la biodiversit\u00e9\">\n                        \n                            <div class=\"zfc-card-image\">\n                                                                    <img decoding=\"async\"\n                                        src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/1200-800-max-1024x683.webp\"\n                                        alt=\"Le Parc Jardin de la Sente des Rivi\u00e8res : Un am\u00e9nagement exemplaire pour la pr\u00e9servation de la biodiversit\u00e9\"\n                                        loading=\"lazy\"\n                                    \/>\n                                                            <\/div>\n\n                            <div class=\"zfc-card-body\">\n                                                                    <span class=\"zfc-card-cat\">projets laur\u00e9ats<\/span>\n                                                                <h3 class=\"zfc-card-title\"><span class=\"ez-toc-section\" id=\"Le_Parc_Jardin_de_la_Sente_des_Rivieres_Un_amenagement_exemplaire_pour_la_preservation_de_la_biodiversite\"><\/span>Le Parc Jardin de la Sente des Rivi\u00e8res : Un am\u00e9nagement exemplaire pour la pr\u00e9servation de la biodiversit\u00e9<span class=\"ez-toc-section-end\"><\/span><\/h3>\n                                                                    <p class=\"zfc-card-desc\">Laur\u00e9at du Prix sp\u00e9cial \u00ab&nbsp;G\u00e9nie \u00e9cologique en Milieux urbains&nbsp;\u00bb Un projet r\u00e9alis\u00e9 par (porteur de projet et partenaire technique) : Pr\u00e9sentation synth\u00e9tique du projet Ce projet consiste \u00e0 restaurer une ancienne zone humide et \u00e0 am\u00e9nager un espace d\u2019environ 30 000 m\u00b2 en parc jardin d\u00e9di\u00e9 \u00e0 la promenade, la d\u00e9tente, la d\u00e9couverte et la [&hellip;]<\/p>\n                                                            <\/div>\n\n                                                    <\/a>\n                                            <\/div>\n                                    <div class=\"zfc-card\">\n                                                    <a href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/travaux-de-protection-contre-les-crues-et-de-restauration-environnementale-de-la-riviere-yzeron-en-zone-urbaine-a-sainte-foy-les-lyon-rhone\/\" class=\"zfc-card-link\" aria-label=\"Travaux de protection contre les crues et de restauration environnementale de la rivi\u00e8re Yzeron en zone urbaine \u00e0 Sainte Foy-l\u00e8s-Lyon (Rh\u00f4ne)\">\n                        \n                            <div class=\"zfc-card-image\">\n                                                                    <img decoding=\"async\"\n                                        src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/1200-800-max-1024x683.webp\"\n                                        alt=\"Travaux de protection contre les crues et de restauration environnementale de la rivi\u00e8re Yzeron en zone urbaine \u00e0 Sainte Foy-l\u00e8s-Lyon (Rh\u00f4ne)\"\n                                        loading=\"lazy\"\n                                    \/>\n                                                            <\/div>\n\n                            <div class=\"zfc-card-body\">\n                                                                    <span class=\"zfc-card-cat\">projets laur\u00e9ats<\/span>\n                                                                <h3 class=\"zfc-card-title\"><span class=\"ez-toc-section\" id=\"Travaux_de_protection_contre_les_crues_et_de_restauration_environnementale_de_la_riviere_Yzeron_en_zone_urbaine_a_Sainte_Foy-les-Lyon_Rhone\"><\/span>Travaux de protection contre les crues et de restauration environnementale de la rivi\u00e8re Yzeron en zone urbaine \u00e0 Sainte Foy-l\u00e8s-Lyon (Rh\u00f4ne)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n                                                                    <p class=\"zfc-card-desc\">Laur\u00e9at de la cat\u00e9gorie \u00ab&nbsp;Am\u00e9lioration des services rendus par les \u00e9cosyst\u00e8mes et les sols&nbsp;\u00bb Un projet r\u00e9alis\u00e9 par (porteur du projet, partenaire technique et financier) : Le Syndicat Mixte d\u2019Am\u00e9nagement et de Gestion de l\u2019Yzeron, du Ratier et du Charbonni\u00e8res est en charge de la gestion et des am\u00e9nagements des cours d\u2019eau du bassin versant [&hellip;]<\/p>\n                                                            <\/div>\n\n                                                    <\/a>\n                                            <\/div>\n                                    <div class=\"zfc-card\">\n                                                    <a href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/12\/projet-integre-de-restauration-des-milieux-naturels-de-la-reunion\/\" class=\"zfc-card-link\" aria-label=\"Projet int\u00e9gr\u00e9 de restauration des milieux naturels de La R\u00e9union\">\n                        \n                            <div class=\"zfc-card-image\">\n                                                                    <img decoding=\"async\"\n                                        src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Laureat-cat.-3-PGE-2024-Projet-restauration-milieux-naturels-La-Reunion.png\"\n                                        alt=\"Projet int\u00e9gr\u00e9 de restauration des milieux naturels de La R\u00e9union\"\n                                        loading=\"lazy\"\n                                    \/>\n                                                            <\/div>\n\n                            <div class=\"zfc-card-body\">\n                                                                    <span class=\"zfc-card-cat\">projets laur\u00e9ats<\/span>\n                                                                <h3 class=\"zfc-card-title\"><span class=\"ez-toc-section\" id=\"Projet_integre_de_restauration_des_milieux_naturels_de_La_Reunion\"><\/span>Projet int\u00e9gr\u00e9 de restauration des milieux naturels de La R\u00e9union<span class=\"ez-toc-section-end\"><\/span><\/h3>\n                                                                    <p class=\"zfc-card-desc\">Laur\u00e9at de la cat\u00e9gorie \u00ab\u00a0Pratiques de gestion favorables \u00e0 la biodiversit\u00e9 (dont la lutte contre les esp\u00e8ces exotiques envahissantes)\u00a0\u00bb. Un projet r\u00e9alis\u00e9 par (porteur de projet et partenaires) : Pr\u00e9sentation synth\u00e9tique du projet Ce projet de territoire port\u00e9 collectivement formule l\u2019objectif ambitieux d\u2019inverser la tendance \u00e0 la perte de la biodiversit\u00e9 sur l\u2019\u00eele de La [&hellip;]<\/p>\n                                                            <\/div>\n\n                                                    <\/a>\n                                            <\/div>\n                                    <div class=\"zfc-card\">\n                                                    <a href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/10\/restauration-de-la-continuite-ecologique-et-de-lhydromorphologie-du-ruisseau-de-la-vitardiere-76\/\" class=\"zfc-card-link\" aria-label=\"Restauration de la continuit\u00e9 \u00e9cologique et de l\u2019hydromorphologie du ruisseau de la Vitardi\u00e8re (76)\">\n                        \n                            <div class=\"zfc-card-image\">\n                                                                    <img decoding=\"async\"\n                                        src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/06\/Vue-aerienne-terrassemnt-Moulin-Haudricourt-SMAB-BIOTEC-NET-1024x768.jpg\"\n                                        alt=\"Restauration de la continuit\u00e9 \u00e9cologique et de l\u2019hydromorphologie du ruisseau de la Vitardi\u00e8re (76)\"\n                                        loading=\"lazy\"\n                                    \/>\n                                                            <\/div>\n\n                            <div class=\"zfc-card-body\">\n                                                                    <span class=\"zfc-card-cat\">projets laur\u00e9ats<\/span>\n                                                                <h3 class=\"zfc-card-title\"><span class=\"ez-toc-section\" id=\"Restauration_de_la_continuite_ecologique_et_de_lhydromorphologie_du_ruisseau_de_la_Vitardiere_76\"><\/span>Restauration de la continuit\u00e9 \u00e9cologique et de l\u2019hydromorphologie du ruisseau de la Vitardi\u00e8re (76)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n                                                                    <p class=\"zfc-card-desc\">Laur\u00e9at de la cat\u00e9gorie \u00ab\u00a0Am\u00e9lioration de la continuit\u00e9 \u00e9cologique (trames verte, bleue, noire, brune, turquoise ou blanche)\u00a0\u00bb Un projet r\u00e9alis\u00e9 par (3 porteurs de projet et les partenaires) : Pr\u00e9sentation synth\u00e9tique du projet En 2022, le Syndicat de la Bresle a mis en place une ambitieuse op\u00e9ration de restauration morpho- \u00e9cologique d\u2019un des affluents de [&hellip;]<\/p>\n                                                            <\/div>\n\n                                                    <\/a>\n                                            <\/div>\n                                    <div class=\"zfc-card\">\n                                                    <a href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/10\/restauration-des-fonctionnalites-ecologiques-de-la-nivelle-a-ainhoa-64\/\" class=\"zfc-card-link\" aria-label=\"Restauration des fonctionnalit\u00e9s \u00e9cologiques de la Nivelle \u00e0 Ainhoa (64)\">\n                        \n                            <div class=\"zfc-card-image\">\n                                                                    <img decoding=\"async\"\n                                        src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/1200-800-max-1024x683.webp\"\n                                        alt=\"Restauration des fonctionnalit\u00e9s \u00e9cologiques de la Nivelle \u00e0 Ainhoa (64)\"\n                                        loading=\"lazy\"\n                                    \/>\n                                                            <\/div>\n\n                            <div class=\"zfc-card-body\">\n                                                                    <span class=\"zfc-card-cat\">projets laur\u00e9ats<\/span>\n                                                                <h3 class=\"zfc-card-title\"><span class=\"ez-toc-section\" id=\"Restauration_des_fonctionnalites_ecologiques_de_la_Nivelle_a_Ainhoa_64\"><\/span>Restauration des fonctionnalit\u00e9s \u00e9cologiques de la Nivelle \u00e0 Ainhoa (64)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n                                                                    <p class=\"zfc-card-desc\">Laur\u00e9at de la cat\u00e9gorie \u00ab&nbsp;Am\u00e9lioration de la continuit\u00e9 \u00e9cologique (trames verte, bleue, noire, brune, turquoise ou blanche)&nbsp;\u00bb Un projet r\u00e9alis\u00e9 par (porteur de projet et partenaires) : Pr\u00e9sentation synth\u00e9tique du projet La Nivelle est un petit fleuve c\u00f4tier transfrontalier du Pays Basque. Ses 12 premiers kilom\u00e8tres s\u2019\u00e9coulent dans la province de Navarre, en Espagne. Une [&hellip;]<\/p>\n                                                            <\/div>\n\n                                                    <\/a>\n                                            <\/div>\n                                    <div class=\"zfc-card\">\n                                                    <a href=\"https:\/\/a-igeco.fr\/en\/2026\/02\/10\/restauration-du-marais-de-panesiere\/\" class=\"zfc-card-link\" aria-label=\"Restauration du marais de Panesiere\">\n                        \n                            <div class=\"zfc-card-image\">\n                                                                    <img decoding=\"async\"\n                                        src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Restauration-marais-Panesiere-Jura_FDCJ.png\"\n                                        alt=\"Restauration du marais de Panesiere\"\n                                        loading=\"lazy\"\n                                    \/>\n                                                            <\/div>\n\n                            <div class=\"zfc-card-body\">\n                                                                    <span class=\"zfc-card-cat\">projets laur\u00e9ats<\/span>\n                                                                <h3 class=\"zfc-card-title\"><span class=\"ez-toc-section\" id=\"Restauration_du_marais_de_Panesiere\"><\/span>Restauration du marais de Panesiere<span class=\"ez-toc-section-end\"><\/span><\/h3>\n                                                                    <p class=\"zfc-card-desc\">Laur\u00e9at de la cat\u00e9gorie \u201cRestauration de milieux (\u00e9cosyst\u00e8mes, populations)\u201d Un projet r\u00e9alis\u00e9 par (porteur projet, partenaires techniques et financiers) : Pr\u00e9sentation synth\u00e9tique du projet Le projet a permis la restauration d\u2019un cours d\u2019eau et d\u2019un marais de 18 ha, situ\u00e9 sur le second plateau du Jura \u00e0 Chatelneuf (39). Avant sa restauration le marais \u00e9tait [&hellip;]<\/p>\n                                                            <\/div>\n\n                                                    <\/a>\n                                            <\/div>\n                            <\/div>\n        <\/div>\n\n        <div class=\"zfc-nav\">\n            <button class=\"zfc-prev\" aria-label=\"Pr\u00e9c\u00e9dent\">&#8592;<\/button>\n            <span class=\"zfc-counter\"><\/span>\n            <button class=\"zfc-next\" aria-label=\"Suivant\">&#8594;<\/button>\n        <\/div>\n\n    <\/div>\n    \n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Laur\u00e9at du Grand Prix Un projet r\u00e9alis\u00e9 par (porteur projet, partenaires techniques et financiers) : Le SYMBHI (Syndicat Mixte des Bassins Hydrauliques de l\u2019Is\u00e8re) est gestionnaire de la comp\u00e9tence GEMAPI sur le bassin versant de l\u2019Is\u00e8re. Il assure deux principaux objectifs&nbsp;: Pr\u00e9sentation synth\u00e9tique du projet CLe projet Is\u00e8re Amont est un projet de pr\u00e9vention du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[46],"tags":[44],"class_list":["post-1170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projets-laureats","tag-44"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le projet ISERE AMONT, un projet GEMA avant l\u2019heure ! - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure ! - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Laur\u00e9at du Grand Prix Un projet r\u00e9alis\u00e9 par (porteur projet, partenaires techniques et financiers) : Le SYMBHI (Syndicat Mixte des Bassins Hydrauliques de l\u2019Is\u00e8re) est gestionnaire de la comp\u00e9tence GEMAPI sur le bassin versant de l\u2019Is\u00e8re. Il assure deux principaux objectifs&nbsp;: Pr\u00e9sentation synth\u00e9tique du projet CLe projet Is\u00e8re Amont est un projet de pr\u00e9vention du [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-12T13:45:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T17:06:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Laureat-Grand-prix-PGE-2024-Projet-amenagement-integre-Isere-Amont.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Zedd Grenoble\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Zedd Grenoble\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/\"},\"author\":{\"name\":\"Zedd Grenoble\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/person\\\/6f5a1101b8ba27ae82027dacea3ff342\"},\"headline\":\"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure !\",\"datePublished\":\"2026-02-12T13:45:35+00:00\",\"dateModified\":\"2026-07-07T17:06:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/\"},\"wordCount\":433,\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Laureat-Grand-prix-PGE-2024-Projet-amenagement-integre-Isere-Amont.png\",\"keywords\":[\"2024\"],\"articleSection\":[\"projets laur\u00e9ats\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/\",\"name\":\"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure ! - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Laureat-Grand-prix-PGE-2024-Projet-amenagement-integre-Isere-Amont.png\",\"datePublished\":\"2026-02-12T13:45:35+00:00\",\"dateModified\":\"2026-07-07T17:06:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Laureat-Grand-prix-PGE-2024-Projet-amenagement-integre-Isere-Amont.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Laureat-Grand-prix-PGE-2024-Projet-amenagement-integre-Isere-Amont.png\",\"width\":700,\"height\":472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/2026\\\/02\\\/12\\\/le-projet-isere-amont-un-projet-gema-avant-lheure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/person\\\/6f5a1101b8ba27ae82027dacea3ff342\",\"name\":\"Zedd Grenoble\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1fa62f43a1a011863d981a399eae0d6248b8089c3ba038d59f25472521769111?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1fa62f43a1a011863d981a399eae0d6248b8089c3ba038d59f25472521769111?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1fa62f43a1a011863d981a399eae0d6248b8089c3ba038d59f25472521769111?s=96&d=mm&r=g\",\"caption\":\"Zedd Grenoble\"},\"sameAs\":[\"https:\\\/\\\/a-igeco.fr\"],\"url\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/author\\\/zeddgre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure ! - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/","og_locale":"en_US","og_type":"article","og_title":"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure ! - A-Igeco","og_description":"Laur\u00e9at du Grand Prix Un projet r\u00e9alis\u00e9 par (porteur projet, partenaires techniques et financiers) : Le SYMBHI (Syndicat Mixte des Bassins Hydrauliques de l\u2019Is\u00e8re) est gestionnaire de la comp\u00e9tence GEMAPI sur le bassin versant de l\u2019Is\u00e8re. Il assure deux principaux objectifs&nbsp;: Pr\u00e9sentation synth\u00e9tique du projet CLe projet Is\u00e8re Amont est un projet de pr\u00e9vention du [&hellip;]","og_url":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/","og_site_name":"A-Igeco","article_published_time":"2026-02-12T13:45:35+00:00","article_modified_time":"2026-07-07T17:06:23+00:00","og_image":[{"width":700,"height":472,"url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Laureat-Grand-prix-PGE-2024-Projet-amenagement-integre-Isere-Amont.png","type":"image\/png"}],"author":"Zedd Grenoble","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Zedd Grenoble","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#article","isPartOf":{"@id":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/"},"author":{"name":"Zedd Grenoble","@id":"https:\/\/a-igeco.fr\/#\/schema\/person\/6f5a1101b8ba27ae82027dacea3ff342"},"headline":"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure !","datePublished":"2026-02-12T13:45:35+00:00","dateModified":"2026-07-07T17:06:23+00:00","mainEntityOfPage":{"@id":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/"},"wordCount":433,"publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"image":{"@id":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#primaryimage"},"thumbnailUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Laureat-Grand-prix-PGE-2024-Projet-amenagement-integre-Isere-Amont.png","keywords":["2024"],"articleSection":["projets laur\u00e9ats"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/","url":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/","name":"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure ! - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#primaryimage"},"image":{"@id":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#primaryimage"},"thumbnailUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Laureat-Grand-prix-PGE-2024-Projet-amenagement-integre-Isere-Amont.png","datePublished":"2026-02-12T13:45:35+00:00","dateModified":"2026-07-07T17:06:23+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#primaryimage","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Laureat-Grand-prix-PGE-2024-Projet-amenagement-integre-Isere-Amont.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/02\/Laureat-Grand-prix-PGE-2024-Projet-amenagement-integre-Isere-Amont.png","width":700,"height":472},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/2026\/02\/12\/le-projet-isere-amont-un-projet-gema-avant-lheure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Le projet ISERE AMONT, un projet GEMA avant l\u2019heure !"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/a-igeco.fr\/#\/schema\/person\/6f5a1101b8ba27ae82027dacea3ff342","name":"Zedd Grenoble","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/1fa62f43a1a011863d981a399eae0d6248b8089c3ba038d59f25472521769111?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1fa62f43a1a011863d981a399eae0d6248b8089c3ba038d59f25472521769111?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1fa62f43a1a011863d981a399eae0d6248b8089c3ba038d59f25472521769111?s=96&d=mm&r=g","caption":"Zedd Grenoble"},"sameAs":["https:\/\/a-igeco.fr"],"url":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"}]}},"_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/posts\/1170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/comments?post=1170"}],"version-history":[{"count":34,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/posts\/1170\/revisions"}],"predecessor-version":[{"id":19634,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/posts\/1170\/revisions\/19634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media\/19632"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=1170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/categories?post=1170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/tags?post=1170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}