{"id":1656,"date":"2026-02-25T14:30:49","date_gmt":"2026-02-25T13:30:49","guid":{"rendered":"https:\/\/a-igeco.fr\/?page_id=1656"},"modified":"2026-07-13T12:50:44","modified_gmt":"2026-07-13T10:50:44","slug":"association","status":"publish","type":"page","link":"https:\/\/a-igeco.fr\/en\/presentation\/association\/","title":{"rendered":"Objectifs et missions de l&#8217;association"},"content":{"rendered":"\n<div class=\"wp-block-group entete-parent has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#0f664a;min-height:0px\">\n<div class=\"wp-block-group is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-group-is-layout-17c5d975 wp-block-group-is-layout-flex\" style=\"min-height:0px;margin-top:0px;margin-bottom:-100px;padding-top:0;padding-right:0px;padding-bottom:0;padding-left:0px\">\n<div class=\"wp-block-group has-base-color has-text-color has-link-color has-figtree-font-family has-small-font-size wp-elements-fe8312c3c8cca924b6863930861a7f86 is-layout-flow wp-container-core-group-is-layout-e91de34c wp-block-group-is-layout-flow\" style=\"padding-left:70px;font-style:normal;font-weight:700\">\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-box-title\">Sommaire<\/div>\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Sommaire<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/a-igeco.fr\/en\/presentation\/association\/#LA-IGEco_Structurer_et_valoriser_lIngenierie_et_le_Genie_Ecologiques\" >L\u2019A-IG\u00c9co : Structurer et valoriser l\u2019Ing\u00e9nierie et le G\u00e9nie \u00c9cologiques<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/a-igeco.fr\/en\/presentation\/association\/#Presentation_de_lA-IGEco\" >Pr\u00e9sentation de l\u2019A-IG\u00c9co<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/a-igeco.fr\/en\/presentation\/association\/#Nos_objectifs\" >Nos objectifs&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/a-igeco.fr\/en\/presentation\/association\/#Nos_missions_et_axes_de_travail\" >Nos missions et axes de travail&nbsp;<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h1 class=\"wp-block-heading\" style=\"font-style:normal;font-weight:600\"><span class=\"ez-toc-section\" id=\"LA-IGEco_Structurer_et_valoriser_lIngenierie_et_le_Genie_Ecologiques\"><\/span><strong><strong><strong><strong>L\u2019A-IG\u00c9co : Structurer et valoriser l\u2019Ing\u00e9nierie et le G\u00e9nie \u00c9cologiques<\/strong><\/strong><\/strong><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h1>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1830\" height=\"887\" src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore.png\" alt=\"\" class=\"wp-image-20064\" style=\"aspect-ratio:16\/9;object-fit:cover\" srcset=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore.png 1830w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore-300x145.png 300w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore-1024x496.png 1024w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore-768x372.png 768w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore-1536x744.png 1536w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore-1200x582.png 1200w\" sizes=\"auto, (max-width: 1830px) 100vw, 1830px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image alignfull size-large\" style=\"margin-bottom:0\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"82\" src=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/01\/vague-titre-page-enfnat-1024x82.png\" alt=\"\" class=\"wp-image-432\" srcset=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/01\/vague-titre-page-enfnat-1024x82.png 1024w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/01\/vague-titre-page-enfnat-300x24.png 300w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/01\/vague-titre-page-enfnat-768x61.png 768w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/01\/vague-titre-page-enfnat-1200x96.png 1200w, https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/01\/vague-titre-page-enfnat.png 1400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-1731824d wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Presentation_de_lA-IGEco\"><\/span>Pr\u00e9sentation de l\u2019A-IG\u00c9co<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis 2014, l\u2019A-IG\u00c9co (association f\u00e9d\u00e9rative des Acteurs de l\u2019Ing\u00e9nierie et du G\u00e9nie \u00c9cologiques) incarne la dynamique collective des acteurs de la biodiversit\u00e9. Issue d\u2019une initiative du minist\u00e8re de l\u2019\u00c9cologie, l\u2019association f\u00e9d\u00e8re de nombreux professionnels \u00e0 travers nos r\u00e9seaux membres, structurant une fili\u00e8re d\u2019excellence en France et promouvant son rayonnement international.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">T\u00eate de r\u00e9seau nationale, nous structurons la fili\u00e8re et agissons pour renforcer la reconnaissance de ces m\u00e9tiers essentiels \u00e0 la transition \u00e9cologique.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-dd44152e wp-block-group-is-layout-constrained\" style=\"background-color:#0f664a;margin-top:var(--wp--preset--spacing--50);padding-top:0;padding-right:var(--wp--preset--spacing--70);padding-left:var(--wp--preset--spacing--70)\">\n<h2 class=\"wp-block-heading has-base-color has-text-color has-link-color wp-elements-bf8076d132b052e9472c7bb43ec50f3b\" style=\"margin-top:0;margin-bottom:var(--wp--preset--spacing--50);padding-top:var(--wp--preset--spacing--50)\"><span class=\"ez-toc-section\" id=\"Nos_objectifs\"><\/span>Nos objectifs&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-794e3cfa wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"uagb-block-9a4f2429 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Regrouper les r\u00e9seaux existants pour favoriser les \u00e9changes entre tous les acteurs fran\u00e7ais concern\u00e9s par l\u2019ing\u00e9nierie et le g\u00e9nie \u00e9cologiques.&nbsp;<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"uagb-block-fef206da uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Renforcer et valoriser leur niveau de comp\u00e9tences, tout en faisant conna\u00eetre leur expertise et leur savoir-faire.&nbsp;<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"uagb-block-e13d2b75 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top \"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Accompagner le d\u00e9veloppement des march\u00e9s et la structuration de la fili\u00e8re.<\/p><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-1731824d wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" style=\"margin-top:var(--wp--preset--spacing--60)\"><span class=\"ez-toc-section\" id=\"Nos_missions_et_axes_de_travail\"><\/span>Nos missions et axes de travail&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nous facilitons les \u00e9changes entre les acteurs nationaux et internationaux, et maintenons l\u2019excellence de la fili\u00e8re via des guides techniques, des labels et des outils comme l\u2019Annuaire des acteurs.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous structurons l\u2019offre de formation et valorisons la fili\u00e8re \u00e0 travers des \u00e9v\u00e9nements comme le Prix national du G\u00e9nie \u00c9cologique ou notre pr\u00e9sence sur des salons.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous faisons remonter les questions de terrain vers les chercheurs, valorisons les retours d\u2019exp\u00e9rience des praticiens, et assurons le transfert de connaissances vers les d\u00e9cideurs.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous identifions les besoins en expertise, accompagnons le montage de projets d\u2019envergure, et informons en temps r\u00e9el sur les opportunit\u00e9s de partenariats, travaux ou colloques.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, nous \u00e9changeons avec des structures europ\u00e9ennes et internationales pour partager les bonnes pratiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"margin-top:var(--wp--preset--spacing--50)\"><strong>L\u2019ing\u00e9nierie et le g\u00e9nie \u00e9cologiques : des leviers pour la biodiversit\u00e9<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Selon le Journal Officiel (2015), l\u2019<strong>ing\u00e9nierie \u00e9cologique<\/strong> d\u00e9signe l\u2019ensemble des connaissances scientifiques, techniques et pratiques appliqu\u00e9es \u00e0 la gestion des ressources et des am\u00e9nagements, dans le respect des m\u00e9canismes \u00e9cologiques. Le <strong>g\u00e9nie \u00e9cologique<\/strong>, quant \u00e0 lui, en est la mise en \u0153uvre op\u00e9rationnelle, visant \u00e0 <strong>restaurer et renforcer la r\u00e9silience des \u00e9cosyst\u00e8mes<\/strong>. Ces disciplines couvrent un large champ : \u00e9tudes, travaux, gestion, recherche, formation, expertise\u2026&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autant d\u2019outils concrets pour <strong>pr\u00e9server, conserver et restaurer<\/strong> la biodiversit\u00e9 et les services \u00e9cosyst\u00e9miques.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019A-IG\u00c9co : Structurer et valoriser l\u2019Ing\u00e9nierie et le G\u00e9nie \u00c9cologiques Pr\u00e9sentation de l\u2019A-IG\u00c9co Depuis 2014, l\u2019A-IG\u00c9co (association f\u00e9d\u00e9rative des Acteurs de l\u2019Ing\u00e9nierie et du G\u00e9nie \u00c9cologiques) incarne la dynamique collective des acteurs de la biodiversit\u00e9. Issue d\u2019une initiative du minist\u00e8re de l\u2019\u00c9cologie, l\u2019association f\u00e9d\u00e8re de nombreux professionnels \u00e0 travers nos r\u00e9seaux membres, structurant une fili\u00e8re [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1001,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"mod-le-zedd-page","meta":{"_acf_changed":false,"_starter_page_template":"blank","_wpcom_template_layout_category":["posts"],"footnotes":""},"class_list":["post-1656","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Objectifs de l\u2019A-IG\u00c9co : structurer et d\u00e9velopper l\u2019ing\u00e9nierie \u00e9cologique<\/title>\n<meta name=\"description\" content=\"Rejoignez une association engag\u00e9e pour structurer la fili\u00e8re \u00e9cologique en France.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/presentation\/association\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Objectifs de l\u2019A-IG\u00c9co : structurer et d\u00e9velopper l\u2019ing\u00e9nierie \u00e9cologique\" \/>\n<meta property=\"og:description\" content=\"Rejoignez une association engag\u00e9e pour structurer la fili\u00e8re \u00e9cologique en France.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/presentation\/association\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T10:50:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1830\" \/>\n\t<meta property=\"og:image:height\" content=\"887\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/presentation\\\/association\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/presentation\\\/association\\\/\",\"name\":\"Objectifs de l\u2019A-IG\u00c9co : structurer et d\u00e9velopper l\u2019ing\u00e9nierie \u00e9cologique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/presentation\\\/association\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/presentation\\\/association\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Logo_A-IGEco_baseline_bicolore.png\",\"datePublished\":\"2026-02-25T13:30:49+00:00\",\"dateModified\":\"2026-07-13T10:50:44+00:00\",\"description\":\"Rejoignez une association engag\u00e9e pour structurer la fili\u00e8re \u00e9cologique en France.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/presentation\\\/association\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/presentation\\\/association\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/presentation\\\/association\\\/#primaryimage\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Logo_A-IGEco_baseline_bicolore.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Logo_A-IGEco_baseline_bicolore.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/presentation\\\/association\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui sommes-nous ?\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/presentation\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Objectifs et missions de l&rsquo;association\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Objectifs de l\u2019A-IG\u00c9co : structurer et d\u00e9velopper l\u2019ing\u00e9nierie \u00e9cologique","description":"Rejoignez une association engag\u00e9e pour structurer la fili\u00e8re \u00e9cologique en France.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/presentation\/association\/","og_locale":"en_US","og_type":"article","og_title":"Objectifs de l\u2019A-IG\u00c9co : structurer et d\u00e9velopper l\u2019ing\u00e9nierie \u00e9cologique","og_description":"Rejoignez une association engag\u00e9e pour structurer la fili\u00e8re \u00e9cologique en France.","og_url":"https:\/\/a-igeco.fr\/presentation\/association\/","og_site_name":"A-Igeco","article_modified_time":"2026-07-13T10:50:44+00:00","og_image":[{"width":1830,"height":887,"url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/presentation\/association\/","url":"https:\/\/a-igeco.fr\/presentation\/association\/","name":"Objectifs de l\u2019A-IG\u00c9co : structurer et d\u00e9velopper l\u2019ing\u00e9nierie \u00e9cologique","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/a-igeco.fr\/presentation\/association\/#primaryimage"},"image":{"@id":"https:\/\/a-igeco.fr\/presentation\/association\/#primaryimage"},"thumbnailUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore.png","datePublished":"2026-02-25T13:30:49+00:00","dateModified":"2026-07-13T10:50:44+00:00","description":"Rejoignez une association engag\u00e9e pour structurer la fili\u00e8re \u00e9cologique en France.","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/presentation\/association\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/presentation\/association\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/presentation\/association\/#primaryimage","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2026\/07\/Logo_A-IGEco_baseline_bicolore.png"},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/presentation\/association\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Qui sommes-nous ?","item":"https:\/\/a-igeco.fr\/presentation\/"},{"@type":"ListItem","position":3,"name":"Objectifs et missions de l&rsquo;association"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/pages\/1656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/comments?post=1656"}],"version-history":[{"count":25,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/pages\/1656\/revisions"}],"predecessor-version":[{"id":20122,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/pages\/1656\/revisions\/20122"}],"up":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/pages\/1001"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=1656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}