{"id":19578,"date":"2026-07-07T17:28:23","date_gmt":"2026-07-07T15:28:23","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/cpie-terres-de-leure-pays-douche\/"},"modified":"2026-07-07T17:28:23","modified_gmt":"2026-07-07T15:28:23","slug":"cpie-terres-de-leure-pays-douche","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/cpie-terres-de-leure-pays-douche\/","title":{"rendered":"CPIE Terres de l&#8217;Eure Pays d\u2019Ouche"},"content":{"rendered":"<p>Le CPIE Terres de l&#8217;Eure &#8211; Pays d&#8217;Ouche oeuvre sur les th\u00e9matiques de l&#8217;environnement, de l&#8217;alimentation, de la sant\u00e9, et de la valorisation du patrimoine agricole et maraicher local, \u00e0 travers des actions d&#8217;\u00e9ducation, de formations, de gestion et d&#8217;\u00e9tude de l&#8217;environnement, et via la culture, production et valorisation de vari\u00e9t\u00e9s anciennes de l\u00e9gumes et c\u00e9r\u00e9ales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le CPIE Terres de l&#8217;Eure &#8211; Pays d&#8217;Ouche oeuvre sur les th\u00e9matiques de l&#8217;environnement, de l&#8217;alimentation, de la sant\u00e9, et de la valorisation du patrimoine agricole et maraicher local, \u00e0 travers des actions d&#8217;\u00e9ducation, de formations, de gestion et d&#8217;\u00e9tude de l&#8217;environnement, et via la culture, production et valorisation de vari\u00e9t\u00e9s anciennes de l\u00e9gumes et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[670],"perimetre_intervention":[712],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-19578","acteur","type-acteur","status-publish","hentry","type_acteur-association","perimetre_intervention-27-eure"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CPIE Terres de l&#039;Eure Pays d\u2019Ouche - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/cpie-terres-de-leure-pays-douche\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CPIE Terres de l&#039;Eure Pays d\u2019Ouche - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Le CPIE Terres de l&#8217;Eure &#8211; Pays d&#8217;Ouche oeuvre sur les th\u00e9matiques de l&#8217;environnement, de l&#8217;alimentation, de la sant\u00e9, et de la valorisation du patrimoine agricole et maraicher local, \u00e0 travers des actions d&#8217;\u00e9ducation, de formations, de gestion et d&#8217;\u00e9tude de l&#8217;environnement, et via la culture, production et valorisation de vari\u00e9t\u00e9s anciennes de l\u00e9gumes et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/cpie-terres-de-leure-pays-douche\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/cpie-terres-de-leure-pays-douche\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/cpie-terres-de-leure-pays-douche\\\/\",\"name\":\"CPIE Terres de l'Eure Pays d\u2019Ouche - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-07-07T15:28:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/cpie-terres-de-leure-pays-douche\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/cpie-terres-de-leure-pays-douche\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/cpie-terres-de-leure-pays-douche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CPIE Terres de l&rsquo;Eure Pays d\u2019Ouche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CPIE Terres de l'Eure Pays d\u2019Ouche - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/cpie-terres-de-leure-pays-douche\/","og_locale":"en_US","og_type":"article","og_title":"CPIE Terres de l'Eure Pays d\u2019Ouche - A-Igeco","og_description":"Le CPIE Terres de l&#8217;Eure &#8211; Pays d&#8217;Ouche oeuvre sur les th\u00e9matiques de l&#8217;environnement, de l&#8217;alimentation, de la sant\u00e9, et de la valorisation du patrimoine agricole et maraicher local, \u00e0 travers des actions d&#8217;\u00e9ducation, de formations, de gestion et d&#8217;\u00e9tude de l&#8217;environnement, et via la culture, production et valorisation de vari\u00e9t\u00e9s anciennes de l\u00e9gumes et [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/cpie-terres-de-leure-pays-douche\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/cpie-terres-de-leure-pays-douche\/","url":"https:\/\/a-igeco.fr\/acteurs\/cpie-terres-de-leure-pays-douche\/","name":"CPIE Terres de l'Eure Pays d\u2019Ouche - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-07-07T15:28:23+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/cpie-terres-de-leure-pays-douche\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/cpie-terres-de-leure-pays-douche\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/cpie-terres-de-leure-pays-douche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"CPIE Terres de l&rsquo;Eure Pays d\u2019Ouche"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Le CPIE Terres de l&#8217;Eure &#8211; Pays d&#8217;Ouche oeuvre sur les th\u00e9matiques de l&#8217;environnement, de l&#8217;alimentation, de la sant\u00e9, et de la valorisation du patrimoine agricole et maraicher local, \u00e0 travers des actions d&#8217;\u00e9ducation, de formations, de gestion et d&#8217;\u00e9tude de l&#8217;environnement, et via la culture, production et valorisation de vari\u00e9t\u00e9s anciennes de l\u00e9gumes et&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/19578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=19578"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=19578"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=19578"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=19578"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=19578"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=19578"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=19578"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=19578"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=19578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}