{"id":19538,"date":"2026-07-07T17:20:58","date_gmt":"2026-07-07T15:20:58","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/cpie-bresse-jura\/"},"modified":"2026-07-07T17:28:18","modified_gmt":"2026-07-07T15:28:18","slug":"cpie-bresse-jura","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/cpie-bresse-jura\/","title":{"rendered":"CPIE Bresse Jura"},"content":{"rendered":"<p>Le Centre Permanent d\u2019Initiatives pour l\u2019Environnement (CPIE) Bresse du Jura est une structure associative d\u2019\u00e9ducation \u00e0 l\u2019environnement et aux comportements \u00e9cologiques, de formation professionnelle et d\u2019accompagnement des territoires constitu\u00e9e de professionnels sp\u00e9cialis\u00e9s. Elle a pour finalit\u00e9 d\u2019encourager les comportements plus respectueux de l\u2019environnement gr\u00e2ce au d\u00e9veloppement d\u2019activit\u00e9s \u00e9ducatives, culturelles et \u00e9conomiques dans le cadre de la pr\u00e9servation du milieu naturel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Centre Permanent d\u2019Initiatives pour l\u2019Environnement (CPIE) Bresse du Jura est une structure associative d\u2019\u00e9ducation \u00e0 l\u2019environnement et aux comportements \u00e9cologiques, de formation professionnelle et d\u2019accompagnement des territoires constitu\u00e9e de professionnels sp\u00e9cialis\u00e9s. Elle a pour finalit\u00e9 d\u2019encourager les comportements plus respectueux de l\u2019environnement gr\u00e2ce au d\u00e9veloppement d\u2019activit\u00e9s \u00e9ducatives, culturelles et \u00e9conomiques dans le cadre de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[670],"perimetre_intervention":[706,724,756],"milieux_intervention":[800],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-19538","acteur","type-acteur","status-publish","hentry","type_acteur-association","perimetre_intervention-21-cote-dor","perimetre_intervention-39-jura","perimetre_intervention-71-saone-et-loire","milieux_intervention-milieux-agricoles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CPIE Bresse Jura - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/cpie-bresse-jura\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CPIE Bresse Jura - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Le Centre Permanent d\u2019Initiatives pour l\u2019Environnement (CPIE) Bresse du Jura est une structure associative d\u2019\u00e9ducation \u00e0 l\u2019environnement et aux comportements \u00e9cologiques, de formation professionnelle et d\u2019accompagnement des territoires constitu\u00e9e de professionnels sp\u00e9cialis\u00e9s. Elle a pour finalit\u00e9 d\u2019encourager les comportements plus respectueux de l\u2019environnement gr\u00e2ce au d\u00e9veloppement d\u2019activit\u00e9s \u00e9ducatives, culturelles et \u00e9conomiques dans le cadre de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/cpie-bresse-jura\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T15:28:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/cpie-bresse-jura\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/cpie-bresse-jura\\\/\",\"name\":\"CPIE Bresse Jura - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-07-07T15:20:58+00:00\",\"dateModified\":\"2026-07-07T15:28:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/cpie-bresse-jura\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/cpie-bresse-jura\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/cpie-bresse-jura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CPIE Bresse Jura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CPIE Bresse Jura - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/cpie-bresse-jura\/","og_locale":"en_US","og_type":"article","og_title":"CPIE Bresse Jura - A-Igeco","og_description":"Le Centre Permanent d\u2019Initiatives pour l\u2019Environnement (CPIE) Bresse du Jura est une structure associative d\u2019\u00e9ducation \u00e0 l\u2019environnement et aux comportements \u00e9cologiques, de formation professionnelle et d\u2019accompagnement des territoires constitu\u00e9e de professionnels sp\u00e9cialis\u00e9s. Elle a pour finalit\u00e9 d\u2019encourager les comportements plus respectueux de l\u2019environnement gr\u00e2ce au d\u00e9veloppement d\u2019activit\u00e9s \u00e9ducatives, culturelles et \u00e9conomiques dans le cadre de [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/cpie-bresse-jura\/","og_site_name":"A-Igeco","article_modified_time":"2026-07-07T15:28:18+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/cpie-bresse-jura\/","url":"https:\/\/a-igeco.fr\/acteurs\/cpie-bresse-jura\/","name":"CPIE Bresse Jura - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-07-07T15:20:58+00:00","dateModified":"2026-07-07T15:28:18+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/cpie-bresse-jura\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/cpie-bresse-jura\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/cpie-bresse-jura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"CPIE Bresse Jura"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Le Centre Permanent d\u2019Initiatives pour l\u2019Environnement (CPIE) Bresse du Jura est une structure associative d\u2019\u00e9ducation \u00e0 l\u2019environnement et aux comportements \u00e9cologiques, de formation professionnelle et d\u2019accompagnement des territoires constitu\u00e9e de professionnels sp\u00e9cialis\u00e9s. Elle a pour finalit\u00e9 d\u2019encourager les comportements plus respectueux de l\u2019environnement gr\u00e2ce au d\u00e9veloppement d\u2019activit\u00e9s \u00e9ducatives, culturelles et \u00e9conomiques dans le cadre de&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/19538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=19538"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=19538"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=19538"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=19538"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=19538"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=19538"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=19538"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=19538"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=19538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}