{"id":19529,"date":"2026-07-07T17:20:57","date_gmt":"2026-07-07T15:20:57","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/comite-national-de-la-peche-professionnelle-en-eau-douce\/"},"modified":"2026-07-07T17:28:18","modified_gmt":"2026-07-07T15:28:18","slug":"comite-national-de-la-peche-professionnelle-en-eau-douce","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/comite-national-de-la-peche-professionnelle-en-eau-douce\/","title":{"rendered":"Comit\u00e9 national de la p\u00eache professionnelle en eau douce"},"content":{"rendered":"<p>Le Conapped est l\u2019interlocuteur des pouvoirs publics au niveau national : minist\u00e8res de de la Transition \u00e9cologique et solidaire, de l\u2019Agriculture, Office fran\u00e7ais de la biodiversit\u00e9 (OFB), France Agrimer. Il assure un suivi des dossiers dans les instances nationales telles que le Comit\u00e9 national de l\u2019eau (avec ses commissions de suivi hydrologique et p\u00eache, cette derni\u00e8re donnant les avis sur les modifications de la r\u00e9glementation de la p\u00eache en eau douce), le Comit\u00e9 national PCB, le Comit\u00e9 national anguille, le Comit\u00e9 national de la biodiversit\u00e9,\u2026), contribue au Conseil sp\u00e9cialis\u00e9 pour les produits de la mer, de l\u2019aquaculture et de la p\u00eache professionnelle en eau douce.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Conapped est l\u2019interlocuteur des pouvoirs publics au niveau national : minist\u00e8res de de la Transition \u00e9cologique et solidaire, de l\u2019Agriculture, Office fran\u00e7ais de la biodiversit\u00e9 (OFB), France Agrimer. Il assure un suivi des dossiers dans les instances nationales telles que le Comit\u00e9 national de l\u2019eau (avec ses commissions de suivi hydrologique et p\u00eache, cette [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[672],"perimetre_intervention":[1067],"milieux_intervention":[],"domaine_activite":[808],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-19529","acteur","type-acteur","status-publish","hentry","type_acteur-syndicat","perimetre_intervention-france-entiere","domaine_activite-gestion-milieux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comit\u00e9 national de la p\u00eache professionnelle en eau douce - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/comite-national-de-la-peche-professionnelle-en-eau-douce\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comit\u00e9 national de la p\u00eache professionnelle en eau douce - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Le Conapped est l\u2019interlocuteur des pouvoirs publics au niveau national : minist\u00e8res de de la Transition \u00e9cologique et solidaire, de l\u2019Agriculture, Office fran\u00e7ais de la biodiversit\u00e9 (OFB), France Agrimer. Il assure un suivi des dossiers dans les instances nationales telles que le Comit\u00e9 national de l\u2019eau (avec ses commissions de suivi hydrologique et p\u00eache, cette [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/comite-national-de-la-peche-professionnelle-en-eau-douce\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T15:28:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/comite-national-de-la-peche-professionnelle-en-eau-douce\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/comite-national-de-la-peche-professionnelle-en-eau-douce\\\/\",\"name\":\"Comit\u00e9 national de la p\u00eache professionnelle en eau douce - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-07-07T15:20:57+00:00\",\"dateModified\":\"2026-07-07T15:28:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/comite-national-de-la-peche-professionnelle-en-eau-douce\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/comite-national-de-la-peche-professionnelle-en-eau-douce\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/comite-national-de-la-peche-professionnelle-en-eau-douce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comit\u00e9 national de la p\u00eache professionnelle en eau douce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comit\u00e9 national de la p\u00eache professionnelle en eau douce - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/comite-national-de-la-peche-professionnelle-en-eau-douce\/","og_locale":"en_US","og_type":"article","og_title":"Comit\u00e9 national de la p\u00eache professionnelle en eau douce - A-Igeco","og_description":"Le Conapped est l\u2019interlocuteur des pouvoirs publics au niveau national : minist\u00e8res de de la Transition \u00e9cologique et solidaire, de l\u2019Agriculture, Office fran\u00e7ais de la biodiversit\u00e9 (OFB), France Agrimer. Il assure un suivi des dossiers dans les instances nationales telles que le Comit\u00e9 national de l\u2019eau (avec ses commissions de suivi hydrologique et p\u00eache, cette [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/comite-national-de-la-peche-professionnelle-en-eau-douce\/","og_site_name":"A-Igeco","article_modified_time":"2026-07-07T15:28:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/comite-national-de-la-peche-professionnelle-en-eau-douce\/","url":"https:\/\/a-igeco.fr\/acteurs\/comite-national-de-la-peche-professionnelle-en-eau-douce\/","name":"Comit\u00e9 national de la p\u00eache professionnelle en eau douce - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-07-07T15:20:57+00:00","dateModified":"2026-07-07T15:28:18+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/comite-national-de-la-peche-professionnelle-en-eau-douce\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/comite-national-de-la-peche-professionnelle-en-eau-douce\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/comite-national-de-la-peche-professionnelle-en-eau-douce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Comit\u00e9 national de la p\u00eache professionnelle en eau douce"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Le Conapped est l\u2019interlocuteur des pouvoirs publics au niveau national : minist\u00e8res de de la Transition \u00e9cologique et solidaire, de l\u2019Agriculture, Office fran\u00e7ais de la biodiversit\u00e9 (OFB), France Agrimer. Il assure un suivi des dossiers dans les instances nationales telles que le Comit\u00e9 national de l\u2019eau (avec ses commissions de suivi hydrologique et p\u00eache, cette&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/19529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=19529"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=19529"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=19529"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=19529"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=19529"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=19529"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=19529"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=19529"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=19529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}