{"id":19500,"date":"2026-07-07T17:20:53","date_gmt":"2026-07-07T15:20:53","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\/"},"modified":"2026-07-07T17:28:15","modified_gmt":"2026-07-07T15:28:15","slug":"agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\/","title":{"rendered":"AGAPE &#8211; Agence d&#8217;Urbanisme et de D\u00e9veloppement Durable Lorraine Nord"},"content":{"rendered":"<p>L\u2019AGAPE est l\u2019organisme permanent de conseil et d\u2019\u00e9tude des collectivit\u00e9s locales du Nord Lorrain transfrontalier en mati\u00e8re d\u2019am\u00e9nagement et d\u2019urbanisme.<br \/>\nElle assiste les collectivit\u00e9s publiques dans la conception et la mise en \u0153uvre de politiques d\u2019am\u00e9nagement.<br \/>\nElle tire sa sp\u00e9cificit\u00e9, au sein du r\u00e9seau des Agences d\u2019Urbanisme, du p\u00e9rim\u00e8tre transfrontalier de ses observations, de son implication dans la gouvernance transfrontali\u00e8re, du polycentrisme de son territoire d\u2019intervention.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019AGAPE est l\u2019organisme permanent de conseil et d\u2019\u00e9tude des collectivit\u00e9s locales du Nord Lorrain transfrontalier en mati\u00e8re d\u2019am\u00e9nagement et d\u2019urbanisme. Elle assiste les collectivit\u00e9s publiques dans la conception et la mise en \u0153uvre de politiques d\u2019am\u00e9nagement. Elle tire sa sp\u00e9cificit\u00e9, au sein du r\u00e9seau des Agences d\u2019Urbanisme, du p\u00e9rim\u00e8tre transfrontalier de ses observations, de son [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[670],"perimetre_intervention":[739,740,742],"milieux_intervention":[800,795,793,794,796,797],"domaine_activite":[812,806,804,816],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-19500","acteur","type-acteur","status-publish","hentry","type_acteur-association","perimetre_intervention-54-meurthe-et-moselle","perimetre_intervention-55-meuse","perimetre_intervention-57-moselle","milieux_intervention-milieux-agricoles","milieux_intervention-milieux-forestiers","milieux_intervention-milieux-marins","milieux_intervention-milieux-montagnards","milieux_intervention-milieux-rocheux","milieux_intervention-milieux-urbains","domaine_activite-formation","domaine_activite-geomatique","domaine_activite-planification","domaine_activite-recherche-scientifique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AGAPE - Agence d&#039;Urbanisme et de D\u00e9veloppement Durable Lorraine Nord - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AGAPE - Agence d&#039;Urbanisme et de D\u00e9veloppement Durable Lorraine Nord - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"L\u2019AGAPE est l\u2019organisme permanent de conseil et d\u2019\u00e9tude des collectivit\u00e9s locales du Nord Lorrain transfrontalier en mati\u00e8re d\u2019am\u00e9nagement et d\u2019urbanisme. Elle assiste les collectivit\u00e9s publiques dans la conception et la mise en \u0153uvre de politiques d\u2019am\u00e9nagement. Elle tire sa sp\u00e9cificit\u00e9, au sein du r\u00e9seau des Agences d\u2019Urbanisme, du p\u00e9rim\u00e8tre transfrontalier de ses observations, de son [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T15:28:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\\\/\",\"name\":\"AGAPE - Agence d'Urbanisme et de D\u00e9veloppement Durable Lorraine Nord - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-07-07T15:20:53+00:00\",\"dateModified\":\"2026-07-07T15:28:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AGAPE &#8211; Agence d&rsquo;Urbanisme et de D\u00e9veloppement Durable Lorraine Nord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AGAPE - Agence d'Urbanisme et de D\u00e9veloppement Durable Lorraine Nord - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\/","og_locale":"en_US","og_type":"article","og_title":"AGAPE - Agence d'Urbanisme et de D\u00e9veloppement Durable Lorraine Nord - A-Igeco","og_description":"L\u2019AGAPE est l\u2019organisme permanent de conseil et d\u2019\u00e9tude des collectivit\u00e9s locales du Nord Lorrain transfrontalier en mati\u00e8re d\u2019am\u00e9nagement et d\u2019urbanisme. Elle assiste les collectivit\u00e9s publiques dans la conception et la mise en \u0153uvre de politiques d\u2019am\u00e9nagement. Elle tire sa sp\u00e9cificit\u00e9, au sein du r\u00e9seau des Agences d\u2019Urbanisme, du p\u00e9rim\u00e8tre transfrontalier de ses observations, de son [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\/","og_site_name":"A-Igeco","article_modified_time":"2026-07-07T15:28:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\/","url":"https:\/\/a-igeco.fr\/acteurs\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\/","name":"AGAPE - Agence d'Urbanisme et de D\u00e9veloppement Durable Lorraine Nord - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-07-07T15:20:53+00:00","dateModified":"2026-07-07T15:28:15+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/agape-agence-durbanisme-et-de-developpement-durable-lorraine-nord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"AGAPE &#8211; Agence d&rsquo;Urbanisme et de D\u00e9veloppement Durable Lorraine Nord"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"L\u2019AGAPE est l\u2019organisme permanent de conseil et d\u2019\u00e9tude des collectivit\u00e9s locales du Nord Lorrain transfrontalier en mati\u00e8re d\u2019am\u00e9nagement et d\u2019urbanisme. Elle assiste les collectivit\u00e9s publiques dans la conception et la mise en \u0153uvre de politiques d\u2019am\u00e9nagement. Elle tire sa sp\u00e9cificit\u00e9, au sein du r\u00e9seau des Agences d\u2019Urbanisme, du p\u00e9rim\u00e8tre transfrontalier de ses observations, de son&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/19500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=19500"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=19500"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=19500"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=19500"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=19500"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=19500"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=19500"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=19500"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=19500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}