{"id":19493,"date":"2026-07-07T17:20:52","date_gmt":"2026-07-07T15:20:52","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/association-reserve-naturelle-geologique-saucats-la-brede\/"},"modified":"2026-07-07T17:28:14","modified_gmt":"2026-07-07T15:28:14","slug":"association-reserve-naturelle-geologique-saucats-la-brede","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/association-reserve-naturelle-geologique-saucats-la-brede\/","title":{"rendered":"Association R\u00e9serve Naturelle G\u00e9ologique Saucats-La Br\u00e8de"},"content":{"rendered":"<p>Gestionnaire de la premi\u00e8re r\u00e9serve naturelle g\u00e9ologique de France:  6 sites pr\u00e9sentant des affleurements de fossiles sur les rives du Saucats. Elle propose visites guid\u00e9es, animations scolaires et expertise scientifique sur la g\u00e9ologie et la pal\u00e9ontologie de l&#8217;Aquitain.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gestionnaire de la premi\u00e8re r\u00e9serve naturelle g\u00e9ologique de France: 6 sites pr\u00e9sentant des affleurements de fossiles sur les rives du Saucats. Elle propose visites guid\u00e9es, animations scolaires et expertise scientifique sur la g\u00e9ologie et la pal\u00e9ontologie de l&#8217;Aquitain.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[670,673],"perimetre_intervention":[718],"milieux_intervention":[796],"domaine_activite":[808,802,804,816],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-19493","acteur","type-acteur","status-publish","hentry","type_acteur-association","type_acteur-gestionnaires-espaces","perimetre_intervention-33-gironde","milieux_intervention-milieux-rocheux","domaine_activite-gestion-milieux","domaine_activite-inventaire-diagnostic","domaine_activite-planification","domaine_activite-recherche-scientifique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Association R\u00e9serve Naturelle G\u00e9ologique Saucats-La Br\u00e8de - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/association-reserve-naturelle-geologique-saucats-la-brede\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Association R\u00e9serve Naturelle G\u00e9ologique Saucats-La Br\u00e8de - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Gestionnaire de la premi\u00e8re r\u00e9serve naturelle g\u00e9ologique de France: 6 sites pr\u00e9sentant des affleurements de fossiles sur les rives du Saucats. Elle propose visites guid\u00e9es, animations scolaires et expertise scientifique sur la g\u00e9ologie et la pal\u00e9ontologie de l&#8217;Aquitain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/association-reserve-naturelle-geologique-saucats-la-brede\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T15:28:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-reserve-naturelle-geologique-saucats-la-brede\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-reserve-naturelle-geologique-saucats-la-brede\\\/\",\"name\":\"Association R\u00e9serve Naturelle G\u00e9ologique Saucats-La Br\u00e8de - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-07-07T15:20:52+00:00\",\"dateModified\":\"2026-07-07T15:28:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-reserve-naturelle-geologique-saucats-la-brede\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-reserve-naturelle-geologique-saucats-la-brede\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-reserve-naturelle-geologique-saucats-la-brede\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Association R\u00e9serve Naturelle G\u00e9ologique Saucats-La Br\u00e8de\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association R\u00e9serve Naturelle G\u00e9ologique Saucats-La Br\u00e8de - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/association-reserve-naturelle-geologique-saucats-la-brede\/","og_locale":"en_US","og_type":"article","og_title":"Association R\u00e9serve Naturelle G\u00e9ologique Saucats-La Br\u00e8de - A-Igeco","og_description":"Gestionnaire de la premi\u00e8re r\u00e9serve naturelle g\u00e9ologique de France: 6 sites pr\u00e9sentant des affleurements de fossiles sur les rives du Saucats. Elle propose visites guid\u00e9es, animations scolaires et expertise scientifique sur la g\u00e9ologie et la pal\u00e9ontologie de l&#8217;Aquitain.","og_url":"https:\/\/a-igeco.fr\/acteurs\/association-reserve-naturelle-geologique-saucats-la-brede\/","og_site_name":"A-Igeco","article_modified_time":"2026-07-07T15:28:14+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/association-reserve-naturelle-geologique-saucats-la-brede\/","url":"https:\/\/a-igeco.fr\/acteurs\/association-reserve-naturelle-geologique-saucats-la-brede\/","name":"Association R\u00e9serve Naturelle G\u00e9ologique Saucats-La Br\u00e8de - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-07-07T15:20:52+00:00","dateModified":"2026-07-07T15:28:14+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/association-reserve-naturelle-geologique-saucats-la-brede\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/association-reserve-naturelle-geologique-saucats-la-brede\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/association-reserve-naturelle-geologique-saucats-la-brede\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Association R\u00e9serve Naturelle G\u00e9ologique Saucats-La Br\u00e8de"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Gestionnaire de la premi\u00e8re r\u00e9serve naturelle g\u00e9ologique de France: 6 sites pr\u00e9sentant des affleurements de fossiles sur les rives du Saucats. Elle propose visites guid\u00e9es, animations scolaires et expertise scientifique sur la g\u00e9ologie et la pal\u00e9ontologie de l&#8217;Aquitain.","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/19493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=19493"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=19493"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=19493"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=19493"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=19493"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=19493"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=19493"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=19493"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=19493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}