{"id":19489,"date":"2026-07-07T17:20:52","date_gmt":"2026-07-07T15:20:52","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\/"},"modified":"2026-07-07T17:28:14","modified_gmt":"2026-07-07T15:28:14","slug":"association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\/","title":{"rendered":"Association r\u00e9gionale des F\u00e9d\u00e9rations de P\u00eache et de Protection du Milieu Aquatique de Nouvelle-Aquitaine"},"content":{"rendered":"<p>Structure r\u00e9gionale f\u00e9d\u00e9rant les 12 f\u00e9d\u00e9rations d\u00e9partementales de p\u00eache de Nouvelle-Aquitaine, elle agit pour la pr\u00e9servation de la biodiversit\u00e9 des milieux aquatiques et la promotion de la p\u00eache de loisir sur l&#8217;un des territoires les plus riches de France en termes de cours d&#8217;eau et de zones humides.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Structure r\u00e9gionale f\u00e9d\u00e9rant les 12 f\u00e9d\u00e9rations d\u00e9partementales de p\u00eache de Nouvelle-Aquitaine, elle agit pour la pr\u00e9servation de la biodiversit\u00e9 des milieux aquatiques et la promotion de la p\u00eache de loisir sur l&#8217;un des territoires les plus riches de France en termes de cours d&#8217;eau et de zones humides.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[670],"perimetre_intervention":[700,701,703,708,764,709,718,772,725,732,749,771],"milieux_intervention":[],"domaine_activite":[808,802,804,816,809],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-19489","acteur","type-acteur","status-publish","hentry","type_acteur-association","perimetre_intervention-16-charente","perimetre_intervention-17-charente-maritime","perimetre_intervention-19-correze","perimetre_intervention-23-creuse","perimetre_intervention-79-deux-sevres","perimetre_intervention-24-dordogne","perimetre_intervention-33-gironde","perimetre_intervention-87-haute-vienne","perimetre_intervention-40-landes","perimetre_intervention-47-lot-et-garonne","perimetre_intervention-64-pyrenees-atlantiques","perimetre_intervention-86-vienne","domaine_activite-gestion-milieux","domaine_activite-inventaire-diagnostic","domaine_activite-planification","domaine_activite-recherche-scientifique","domaine_activite-restauration"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Association r\u00e9gionale des F\u00e9d\u00e9rations de P\u00eache et de Protection du Milieu Aquatique de Nouvelle-Aquitaine - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Association r\u00e9gionale des F\u00e9d\u00e9rations de P\u00eache et de Protection du Milieu Aquatique de Nouvelle-Aquitaine - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Structure r\u00e9gionale f\u00e9d\u00e9rant les 12 f\u00e9d\u00e9rations d\u00e9partementales de p\u00eache de Nouvelle-Aquitaine, elle agit pour la pr\u00e9servation de la biodiversit\u00e9 des milieux aquatiques et la promotion de la p\u00eache de loisir sur l&#8217;un des territoires les plus riches de France en termes de cours d&#8217;eau et de zones humides.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T15:28:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\\\/\",\"name\":\"Association r\u00e9gionale des F\u00e9d\u00e9rations de P\u00eache et de Protection du Milieu Aquatique de Nouvelle-Aquitaine - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-07-07T15:20:52+00:00\",\"dateModified\":\"2026-07-07T15:28:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Association r\u00e9gionale des F\u00e9d\u00e9rations de P\u00eache et de Protection du Milieu Aquatique de Nouvelle-Aquitaine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association r\u00e9gionale des F\u00e9d\u00e9rations de P\u00eache et de Protection du Milieu Aquatique de Nouvelle-Aquitaine - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\/","og_locale":"en_US","og_type":"article","og_title":"Association r\u00e9gionale des F\u00e9d\u00e9rations de P\u00eache et de Protection du Milieu Aquatique de Nouvelle-Aquitaine - A-Igeco","og_description":"Structure r\u00e9gionale f\u00e9d\u00e9rant les 12 f\u00e9d\u00e9rations d\u00e9partementales de p\u00eache de Nouvelle-Aquitaine, elle agit pour la pr\u00e9servation de la biodiversit\u00e9 des milieux aquatiques et la promotion de la p\u00eache de loisir sur l&#8217;un des territoires les plus riches de France en termes de cours d&#8217;eau et de zones humides.","og_url":"https:\/\/a-igeco.fr\/acteurs\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\/","og_site_name":"A-Igeco","article_modified_time":"2026-07-07T15:28:14+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\/","url":"https:\/\/a-igeco.fr\/acteurs\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\/","name":"Association r\u00e9gionale des F\u00e9d\u00e9rations de P\u00eache et de Protection du Milieu Aquatique de Nouvelle-Aquitaine - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-07-07T15:20:52+00:00","dateModified":"2026-07-07T15:28:14+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/association-regionale-des-federations-de-peche-et-de-protection-du-milieu-aquatique-de-nouvelle-aquitaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Association r\u00e9gionale des F\u00e9d\u00e9rations de P\u00eache et de Protection du Milieu Aquatique de Nouvelle-Aquitaine"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Structure r\u00e9gionale f\u00e9d\u00e9rant les 12 f\u00e9d\u00e9rations d\u00e9partementales de p\u00eache de Nouvelle-Aquitaine, elle agit pour la pr\u00e9servation de la biodiversit\u00e9 des milieux aquatiques et la promotion de la p\u00eache de loisir sur l&#8217;un des territoires les plus riches de France en termes de cours d&#8217;eau et de zones humides.","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/19489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=19489"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=19489"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=19489"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=19489"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=19489"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=19489"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=19489"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=19489"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=19489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}