{"id":19241,"date":"2026-07-07T17:17:53","date_gmt":"2026-07-07T15:17:53","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/graine-nouvelle-aquitaine\/"},"modified":"2026-07-07T17:27:49","modified_gmt":"2026-07-07T15:27:49","slug":"graine-nouvelle-aquitaine","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/graine-nouvelle-aquitaine\/","title":{"rendered":"GRAINE Nouvelle-Aquitaine"},"content":{"rendered":"<p>Groupe R\u00e9gional d&#8217;Animation et d&#8217;Information sur la Nature et l&#8217;Environnement, c&#8217;est le r\u00e9seau r\u00e9gional des acteurs de l&#8217;\u00e9ducation \u00e0 l&#8217;environnement. Il anime la fili\u00e8re EEDD, mutualise des ressources et coordonne des projets territoriaux en Nouvelle-Aquitaine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Groupe R\u00e9gional d&#8217;Animation et d&#8217;Information sur la Nature et l&#8217;Environnement, c&#8217;est le r\u00e9seau r\u00e9gional des acteurs de l&#8217;\u00e9ducation \u00e0 l&#8217;environnement. Il anime la fili\u00e8re EEDD, mutualise des ressources et coordonne des projets territoriaux en Nouvelle-Aquitaine.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[671],"perimetre_intervention":[700,701,703,708,764,709,718,772,725,732,749,771],"milieux_intervention":[800,795,793,797],"domaine_activite":[812,804],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-19241","acteur","type-acteur","status-publish","hentry","type_acteur-federation","perimetre_intervention-16-charente","perimetre_intervention-17-charente-maritime","perimetre_intervention-19-correze","perimetre_intervention-23-creuse","perimetre_intervention-79-deux-sevres","perimetre_intervention-24-dordogne","perimetre_intervention-33-gironde","perimetre_intervention-87-haute-vienne","perimetre_intervention-40-landes","perimetre_intervention-47-lot-et-garonne","perimetre_intervention-64-pyrenees-atlantiques","perimetre_intervention-86-vienne","milieux_intervention-milieux-agricoles","milieux_intervention-milieux-forestiers","milieux_intervention-milieux-marins","milieux_intervention-milieux-urbains","domaine_activite-formation","domaine_activite-planification"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GRAINE Nouvelle-Aquitaine - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/graine-nouvelle-aquitaine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GRAINE Nouvelle-Aquitaine - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Groupe R\u00e9gional d&#8217;Animation et d&#8217;Information sur la Nature et l&#8217;Environnement, c&#8217;est le r\u00e9seau r\u00e9gional des acteurs de l&#8217;\u00e9ducation \u00e0 l&#8217;environnement. Il anime la fili\u00e8re EEDD, mutualise des ressources et coordonne des projets territoriaux en Nouvelle-Aquitaine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/graine-nouvelle-aquitaine\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T15:27:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/graine-nouvelle-aquitaine\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/graine-nouvelle-aquitaine\\\/\",\"name\":\"GRAINE Nouvelle-Aquitaine - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-07-07T15:17:53+00:00\",\"dateModified\":\"2026-07-07T15:27:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/graine-nouvelle-aquitaine\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/graine-nouvelle-aquitaine\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/graine-nouvelle-aquitaine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GRAINE Nouvelle-Aquitaine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GRAINE Nouvelle-Aquitaine - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/graine-nouvelle-aquitaine\/","og_locale":"en_US","og_type":"article","og_title":"GRAINE Nouvelle-Aquitaine - A-Igeco","og_description":"Groupe R\u00e9gional d&#8217;Animation et d&#8217;Information sur la Nature et l&#8217;Environnement, c&#8217;est le r\u00e9seau r\u00e9gional des acteurs de l&#8217;\u00e9ducation \u00e0 l&#8217;environnement. Il anime la fili\u00e8re EEDD, mutualise des ressources et coordonne des projets territoriaux en Nouvelle-Aquitaine.","og_url":"https:\/\/a-igeco.fr\/acteurs\/graine-nouvelle-aquitaine\/","og_site_name":"A-Igeco","article_modified_time":"2026-07-07T15:27:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/graine-nouvelle-aquitaine\/","url":"https:\/\/a-igeco.fr\/acteurs\/graine-nouvelle-aquitaine\/","name":"GRAINE Nouvelle-Aquitaine - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-07-07T15:17:53+00:00","dateModified":"2026-07-07T15:27:49+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/graine-nouvelle-aquitaine\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/graine-nouvelle-aquitaine\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/graine-nouvelle-aquitaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"GRAINE Nouvelle-Aquitaine"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Groupe R\u00e9gional d&#8217;Animation et d&#8217;Information sur la Nature et l&#8217;Environnement, c&#8217;est le r\u00e9seau r\u00e9gional des acteurs de l&#8217;\u00e9ducation \u00e0 l&#8217;environnement. Il anime la fili\u00e8re EEDD, mutualise des ressources et coordonne des projets territoriaux en Nouvelle-Aquitaine.","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/19241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=19241"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=19241"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=19241"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=19241"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=19241"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=19241"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=19241"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=19241"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=19241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}