{"id":19174,"date":"2026-07-07T17:17:44","date_gmt":"2026-07-07T15:17:44","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/federation-regionale-des-chasseurs-bourgogne-franche-comte\/"},"modified":"2026-07-07T17:27:44","modified_gmt":"2026-07-07T15:27:44","slug":"federation-regionale-des-chasseurs-bourgogne-franche-comte","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/federation-regionale-des-chasseurs-bourgogne-franche-comte\/","title":{"rendered":"F\u00e9d\u00e9ration R\u00e9gionale des Chasseurs Bourgogne Franche-Comt\u00e9"},"content":{"rendered":"<p>Organisme de coordination r\u00e9gionale pour la gestion de la faune sauvage et des habitats. Elle m\u00e8ne des \u00e9tudes scientifiques, des actions de pr\u00e9servation de la biodiversit\u00e9 et assure l&#8217;\u00e9ducation \u00e0 la nature aupr\u00e8s du public.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organisme de coordination r\u00e9gionale pour la gestion de la faune sauvage et des habitats. Elle m\u00e8ne des \u00e9tudes scientifiques, des actions de pr\u00e9servation de la biodiversit\u00e9 et assure l&#8217;\u00e9ducation \u00e0 la nature aupr\u00e8s du public.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[671],"perimetre_intervention":[706,710,755,724,743,756,775,774],"milieux_intervention":[800,795],"domaine_activite":[808,816],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-19174","acteur","type-acteur","status-publish","hentry","type_acteur-federation","perimetre_intervention-21-cote-dor","perimetre_intervention-25-doubs","perimetre_intervention-70-haute-saone","perimetre_intervention-39-jura","perimetre_intervention-58-nievre","perimetre_intervention-71-saone-et-loire","perimetre_intervention-90-territoire-de-belfort","perimetre_intervention-89-yonne","milieux_intervention-milieux-agricoles","milieux_intervention-milieux-forestiers","domaine_activite-gestion-milieux","domaine_activite-recherche-scientifique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00e9d\u00e9ration R\u00e9gionale des Chasseurs Bourgogne Franche-Comt\u00e9 - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/federation-regionale-des-chasseurs-bourgogne-franche-comte\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00e9d\u00e9ration R\u00e9gionale des Chasseurs Bourgogne Franche-Comt\u00e9 - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Organisme de coordination r\u00e9gionale pour la gestion de la faune sauvage et des habitats. Elle m\u00e8ne des \u00e9tudes scientifiques, des actions de pr\u00e9servation de la biodiversit\u00e9 et assure l&#8217;\u00e9ducation \u00e0 la nature aupr\u00e8s du public.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/federation-regionale-des-chasseurs-bourgogne-franche-comte\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T15:27:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/federation-regionale-des-chasseurs-bourgogne-franche-comte\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/federation-regionale-des-chasseurs-bourgogne-franche-comte\\\/\",\"name\":\"F\u00e9d\u00e9ration R\u00e9gionale des Chasseurs Bourgogne Franche-Comt\u00e9 - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-07-07T15:17:44+00:00\",\"dateModified\":\"2026-07-07T15:27:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/federation-regionale-des-chasseurs-bourgogne-franche-comte\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/federation-regionale-des-chasseurs-bourgogne-franche-comte\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/federation-regionale-des-chasseurs-bourgogne-franche-comte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"F\u00e9d\u00e9ration R\u00e9gionale des Chasseurs Bourgogne Franche-Comt\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00e9d\u00e9ration R\u00e9gionale des Chasseurs Bourgogne Franche-Comt\u00e9 - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/federation-regionale-des-chasseurs-bourgogne-franche-comte\/","og_locale":"en_US","og_type":"article","og_title":"F\u00e9d\u00e9ration R\u00e9gionale des Chasseurs Bourgogne Franche-Comt\u00e9 - A-Igeco","og_description":"Organisme de coordination r\u00e9gionale pour la gestion de la faune sauvage et des habitats. Elle m\u00e8ne des \u00e9tudes scientifiques, des actions de pr\u00e9servation de la biodiversit\u00e9 et assure l&#8217;\u00e9ducation \u00e0 la nature aupr\u00e8s du public.","og_url":"https:\/\/a-igeco.fr\/acteurs\/federation-regionale-des-chasseurs-bourgogne-franche-comte\/","og_site_name":"A-Igeco","article_modified_time":"2026-07-07T15:27:44+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/federation-regionale-des-chasseurs-bourgogne-franche-comte\/","url":"https:\/\/a-igeco.fr\/acteurs\/federation-regionale-des-chasseurs-bourgogne-franche-comte\/","name":"F\u00e9d\u00e9ration R\u00e9gionale des Chasseurs Bourgogne Franche-Comt\u00e9 - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-07-07T15:17:44+00:00","dateModified":"2026-07-07T15:27:44+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/federation-regionale-des-chasseurs-bourgogne-franche-comte\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/federation-regionale-des-chasseurs-bourgogne-franche-comte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/federation-regionale-des-chasseurs-bourgogne-franche-comte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"F\u00e9d\u00e9ration R\u00e9gionale des Chasseurs Bourgogne Franche-Comt\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Organisme de coordination r\u00e9gionale pour la gestion de la faune sauvage et des habitats. Elle m\u00e8ne des \u00e9tudes scientifiques, des actions de pr\u00e9servation de la biodiversit\u00e9 et assure l&#8217;\u00e9ducation \u00e0 la nature aupr\u00e8s du public.","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/19174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=19174"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=19174"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=19174"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=19174"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=19174"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=19174"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=19174"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=19174"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=19174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}