{"id":19109,"date":"2026-07-07T17:17:37","date_gmt":"2026-07-07T15:17:37","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/federation-departementale-des-chasseurs-seine-et-marne-breau\/"},"modified":"2026-07-07T17:27:38","modified_gmt":"2026-07-07T15:27:38","slug":"federation-departementale-des-chasseurs-seine-et-marne-breau","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/federation-departementale-des-chasseurs-seine-et-marne-breau\/","title":{"rendered":"F\u00e9d\u00e9ration d\u00e9partementale des chasseurs &#8211; Seine-et-Marne &#8211; Br\u00e9au"},"content":{"rendered":"<p>Les f\u00e9d\u00e9rations d\u00e9partementales de chasse (FDC) sont des associations agr\u00e9\u00e9es qui repr\u00e9sentent les chasseurs au niveau local. Elles ont pour missions principales la gestion durable des populations de gibier, la pr\u00e9servation des habitats naturels et la promotion de la biodiversit\u00e9. Elles agissent en partenariat avec les acteurs publics et priv\u00e9s pour concilier pratique cyn\u00e9g\u00e9tique, \u00e9quilibre des \u00e9cosyst\u00e8mes et protection de l\u2019environnement. Les FDC sensibilisent aussi le public \u00e0 la richesse du patrimoine faunique et floristique, tout en participant activement \u00e0 la police de la chasse et \u00e0 la s\u00e9curit\u00e9 des pratiques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les f\u00e9d\u00e9rations d\u00e9partementales de chasse (FDC) sont des associations agr\u00e9\u00e9es qui repr\u00e9sentent les chasseurs au niveau local. Elles ont pour missions principales la gestion durable des populations de gibier, la pr\u00e9servation des habitats naturels et la promotion de la biodiversit\u00e9. Elles agissent en partenariat avec les acteurs publics et priv\u00e9s pour concilier pratique cyn\u00e9g\u00e9tique, \u00e9quilibre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[670,671],"perimetre_intervention":[762],"milieux_intervention":[795],"domaine_activite":[808],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-19109","acteur","type-acteur","status-publish","hentry","type_acteur-association","type_acteur-federation","perimetre_intervention-77-seine-et-marne","milieux_intervention-milieux-forestiers","domaine_activite-gestion-milieux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00e9d\u00e9ration d\u00e9partementale des chasseurs - Seine-et-Marne - Br\u00e9au - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/federation-departementale-des-chasseurs-seine-et-marne-breau\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00e9d\u00e9ration d\u00e9partementale des chasseurs - Seine-et-Marne - Br\u00e9au - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Les f\u00e9d\u00e9rations d\u00e9partementales de chasse (FDC) sont des associations agr\u00e9\u00e9es qui repr\u00e9sentent les chasseurs au niveau local. Elles ont pour missions principales la gestion durable des populations de gibier, la pr\u00e9servation des habitats naturels et la promotion de la biodiversit\u00e9. Elles agissent en partenariat avec les acteurs publics et priv\u00e9s pour concilier pratique cyn\u00e9g\u00e9tique, \u00e9quilibre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/federation-departementale-des-chasseurs-seine-et-marne-breau\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T15:27:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/federation-departementale-des-chasseurs-seine-et-marne-breau\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/federation-departementale-des-chasseurs-seine-et-marne-breau\\\/\",\"name\":\"F\u00e9d\u00e9ration d\u00e9partementale des chasseurs - Seine-et-Marne - Br\u00e9au - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-07-07T15:17:37+00:00\",\"dateModified\":\"2026-07-07T15:27:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/federation-departementale-des-chasseurs-seine-et-marne-breau\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/federation-departementale-des-chasseurs-seine-et-marne-breau\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/federation-departementale-des-chasseurs-seine-et-marne-breau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"F\u00e9d\u00e9ration d\u00e9partementale des chasseurs &#8211; Seine-et-Marne &#8211; Br\u00e9au\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00e9d\u00e9ration d\u00e9partementale des chasseurs - Seine-et-Marne - Br\u00e9au - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/federation-departementale-des-chasseurs-seine-et-marne-breau\/","og_locale":"en_US","og_type":"article","og_title":"F\u00e9d\u00e9ration d\u00e9partementale des chasseurs - Seine-et-Marne - Br\u00e9au - A-Igeco","og_description":"Les f\u00e9d\u00e9rations d\u00e9partementales de chasse (FDC) sont des associations agr\u00e9\u00e9es qui repr\u00e9sentent les chasseurs au niveau local. Elles ont pour missions principales la gestion durable des populations de gibier, la pr\u00e9servation des habitats naturels et la promotion de la biodiversit\u00e9. Elles agissent en partenariat avec les acteurs publics et priv\u00e9s pour concilier pratique cyn\u00e9g\u00e9tique, \u00e9quilibre [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/federation-departementale-des-chasseurs-seine-et-marne-breau\/","og_site_name":"A-Igeco","article_modified_time":"2026-07-07T15:27:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/federation-departementale-des-chasseurs-seine-et-marne-breau\/","url":"https:\/\/a-igeco.fr\/acteurs\/federation-departementale-des-chasseurs-seine-et-marne-breau\/","name":"F\u00e9d\u00e9ration d\u00e9partementale des chasseurs - Seine-et-Marne - Br\u00e9au - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-07-07T15:17:37+00:00","dateModified":"2026-07-07T15:27:38+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/federation-departementale-des-chasseurs-seine-et-marne-breau\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/federation-departementale-des-chasseurs-seine-et-marne-breau\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/federation-departementale-des-chasseurs-seine-et-marne-breau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"F\u00e9d\u00e9ration d\u00e9partementale des chasseurs &#8211; Seine-et-Marne &#8211; Br\u00e9au"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Les f\u00e9d\u00e9rations d\u00e9partementales de chasse (FDC) sont des associations agr\u00e9\u00e9es qui repr\u00e9sentent les chasseurs au niveau local. Elles ont pour missions principales la gestion durable des populations de gibier, la pr\u00e9servation des habitats naturels et la promotion de la biodiversit\u00e9. Elles agissent en partenariat avec les acteurs publics et priv\u00e9s pour concilier pratique cyn\u00e9g\u00e9tique, \u00e9quilibre&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/19109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=19109"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=19109"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=19109"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=19109"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=19109"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=19109"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=19109"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=19109"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=19109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}