{"id":19026,"date":"2026-07-07T17:17:26","date_gmt":"2026-07-07T15:17:26","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/espaces-naturels-de-la-metropole-europeenne-de-lille\/"},"modified":"2026-07-07T17:27:32","modified_gmt":"2026-07-07T15:27:32","slug":"espaces-naturels-de-la-metropole-europeenne-de-lille","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/espaces-naturels-de-la-metropole-europeenne-de-lille\/","title":{"rendered":"Espaces Naturels de la M\u00e9tropole Europ\u00e9enne de Lille"},"content":{"rendered":"<p>L&#8217;ENM porte la politique de pr\u00e9servation et de valorisation de la biodiversit\u00e9 de la M\u00e9tropole Europ\u00e9enne de Lille. Ses \u00e9quipes assurent la gestion de plus de 1 300 hectares d&#8217;espaces naturels, d\u00e9veloppent la connaissance naturaliste du territoire et accompagnent les communes dans leurs projets de renaturation. \u00c0 travers des actions de g\u00e9nie \u00e9cologique, des inventaires faune-flore, des programmes de restauration des continuit\u00e9s \u00e9cologiques et une offre importante d&#8217;animations nature, l&#8217;ENM \u0153uvre \u00e0 renforcer la place du vivant dans un territoire fortement urbanis\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ENM porte la politique de pr\u00e9servation et de valorisation de la biodiversit\u00e9 de la M\u00e9tropole Europ\u00e9enne de Lille. Ses \u00e9quipes assurent la gestion de plus de 1 300 hectares d&#8217;espaces naturels, d\u00e9veloppent la connaissance naturaliste du territoire et accompagnent les communes dans leurs projets de renaturation. \u00c0 travers des actions de g\u00e9nie \u00e9cologique, des inventaires [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[677],"perimetre_intervention":[744],"milieux_intervention":[800,795,797],"domaine_activite":[808,802,804,816,809,810],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-19026","acteur","type-acteur","status-publish","hentry","type_acteur-collectivite","perimetre_intervention-59-nord","milieux_intervention-milieux-agricoles","milieux_intervention-milieux-forestiers","milieux_intervention-milieux-urbains","domaine_activite-gestion-milieux","domaine_activite-inventaire-diagnostic","domaine_activite-planification","domaine_activite-recherche-scientifique","domaine_activite-restauration","domaine_activite-travaux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espaces Naturels de la M\u00e9tropole Europ\u00e9enne de Lille - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/espaces-naturels-de-la-metropole-europeenne-de-lille\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espaces Naturels de la M\u00e9tropole Europ\u00e9enne de Lille - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"L&#8217;ENM porte la politique de pr\u00e9servation et de valorisation de la biodiversit\u00e9 de la M\u00e9tropole Europ\u00e9enne de Lille. Ses \u00e9quipes assurent la gestion de plus de 1 300 hectares d&#8217;espaces naturels, d\u00e9veloppent la connaissance naturaliste du territoire et accompagnent les communes dans leurs projets de renaturation. \u00c0 travers des actions de g\u00e9nie \u00e9cologique, des inventaires [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/espaces-naturels-de-la-metropole-europeenne-de-lille\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T15:27:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/espaces-naturels-de-la-metropole-europeenne-de-lille\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/espaces-naturels-de-la-metropole-europeenne-de-lille\\\/\",\"name\":\"Espaces Naturels de la M\u00e9tropole Europ\u00e9enne de Lille - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-07-07T15:17:26+00:00\",\"dateModified\":\"2026-07-07T15:27:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/espaces-naturels-de-la-metropole-europeenne-de-lille\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/espaces-naturels-de-la-metropole-europeenne-de-lille\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/espaces-naturels-de-la-metropole-europeenne-de-lille\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Espaces Naturels de la M\u00e9tropole Europ\u00e9enne de Lille\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espaces Naturels de la M\u00e9tropole Europ\u00e9enne de Lille - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/espaces-naturels-de-la-metropole-europeenne-de-lille\/","og_locale":"en_US","og_type":"article","og_title":"Espaces Naturels de la M\u00e9tropole Europ\u00e9enne de Lille - A-Igeco","og_description":"L&#8217;ENM porte la politique de pr\u00e9servation et de valorisation de la biodiversit\u00e9 de la M\u00e9tropole Europ\u00e9enne de Lille. Ses \u00e9quipes assurent la gestion de plus de 1 300 hectares d&#8217;espaces naturels, d\u00e9veloppent la connaissance naturaliste du territoire et accompagnent les communes dans leurs projets de renaturation. \u00c0 travers des actions de g\u00e9nie \u00e9cologique, des inventaires [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/espaces-naturels-de-la-metropole-europeenne-de-lille\/","og_site_name":"A-Igeco","article_modified_time":"2026-07-07T15:27:32+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/espaces-naturels-de-la-metropole-europeenne-de-lille\/","url":"https:\/\/a-igeco.fr\/acteurs\/espaces-naturels-de-la-metropole-europeenne-de-lille\/","name":"Espaces Naturels de la M\u00e9tropole Europ\u00e9enne de Lille - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-07-07T15:17:26+00:00","dateModified":"2026-07-07T15:27:32+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/espaces-naturels-de-la-metropole-europeenne-de-lille\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/espaces-naturels-de-la-metropole-europeenne-de-lille\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/espaces-naturels-de-la-metropole-europeenne-de-lille\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Espaces Naturels de la M\u00e9tropole Europ\u00e9enne de Lille"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"L&#8217;ENM porte la politique de pr\u00e9servation et de valorisation de la biodiversit\u00e9 de la M\u00e9tropole Europ\u00e9enne de Lille. Ses \u00e9quipes assurent la gestion de plus de 1 300 hectares d&#8217;espaces naturels, d\u00e9veloppent la connaissance naturaliste du territoire et accompagnent les communes dans leurs projets de renaturation. \u00c0 travers des actions de g\u00e9nie \u00e9cologique, des inventaires&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/19026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=19026"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=19026"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=19026"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=19026"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=19026"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=19026"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=19026"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=19026"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=19026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}