{"id":18836,"date":"2026-07-07T17:17:03","date_gmt":"2026-07-07T15:17:03","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\/"},"modified":"2026-07-07T17:27:17","modified_gmt":"2026-07-07T15:27:17","slug":"association-de-mise-en-valeur-des-sites-naturels-de-glomel","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\/","title":{"rendered":"Association de mise en valeur des sites naturels de Glomel"},"content":{"rendered":"<p>Au c\u0153ur des Montagnes Noires, la r\u00e9serve naturelle r\u00e9gionale des landes et marais de Glomel regroupe sur 108 hectares deux sites distants d\u2019une dizaine de kilom\u00e8tres. L\u2019ensemble comprend des Milieux rares et diversifi\u00e9s : landes humides \u00e0 tourbeuses, groupements de tourbi\u00e8res, prairies humides oligotrophes, saulaies boulaies hygrophiles, ch\u00eanaies acidophiles ainsi que quelques m\u00e9gaphorbiaies.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au c\u0153ur des Montagnes Noires, la r\u00e9serve naturelle r\u00e9gionale des landes et marais de Glomel regroupe sur 108 hectares deux sites distants d\u2019une dizaine de kilom\u00e8tres. L\u2019ensemble comprend des Milieux rares et diversifi\u00e9s : landes humides \u00e0 tourbeuses, groupements de tourbi\u00e8res, prairies humides oligotrophes, saulaies boulaies hygrophiles, ch\u00eanaies acidophiles ainsi que quelques m\u00e9gaphorbiaies.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[670,673],"perimetre_intervention":[707],"milieux_intervention":[795],"domaine_activite":[808,809],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-18836","acteur","type-acteur","status-publish","hentry","type_acteur-association","type_acteur-gestionnaires-espaces","perimetre_intervention-22-cotes-darmor","milieux_intervention-milieux-forestiers","domaine_activite-gestion-milieux","domaine_activite-restauration"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Association de mise en valeur des sites naturels de Glomel - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Association de mise en valeur des sites naturels de Glomel - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Au c\u0153ur des Montagnes Noires, la r\u00e9serve naturelle r\u00e9gionale des landes et marais de Glomel regroupe sur 108 hectares deux sites distants d\u2019une dizaine de kilom\u00e8tres. L\u2019ensemble comprend des Milieux rares et diversifi\u00e9s : landes humides \u00e0 tourbeuses, groupements de tourbi\u00e8res, prairies humides oligotrophes, saulaies boulaies hygrophiles, ch\u00eanaies acidophiles ainsi que quelques m\u00e9gaphorbiaies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T15:27:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\\\/\",\"name\":\"Association de mise en valeur des sites naturels de Glomel - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-07-07T15:17:03+00:00\",\"dateModified\":\"2026-07-07T15:27:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Association de mise en valeur des sites naturels de Glomel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Association de mise en valeur des sites naturels de Glomel - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\/","og_locale":"en_US","og_type":"article","og_title":"Association de mise en valeur des sites naturels de Glomel - A-Igeco","og_description":"Au c\u0153ur des Montagnes Noires, la r\u00e9serve naturelle r\u00e9gionale des landes et marais de Glomel regroupe sur 108 hectares deux sites distants d\u2019une dizaine de kilom\u00e8tres. L\u2019ensemble comprend des Milieux rares et diversifi\u00e9s : landes humides \u00e0 tourbeuses, groupements de tourbi\u00e8res, prairies humides oligotrophes, saulaies boulaies hygrophiles, ch\u00eanaies acidophiles ainsi que quelques m\u00e9gaphorbiaies.","og_url":"https:\/\/a-igeco.fr\/acteurs\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\/","og_site_name":"A-Igeco","article_modified_time":"2026-07-07T15:27:17+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\/","url":"https:\/\/a-igeco.fr\/acteurs\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\/","name":"Association de mise en valeur des sites naturels de Glomel - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-07-07T15:17:03+00:00","dateModified":"2026-07-07T15:27:17+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/association-de-mise-en-valeur-des-sites-naturels-de-glomel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Association de mise en valeur des sites naturels de Glomel"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Au c\u0153ur des Montagnes Noires, la r\u00e9serve naturelle r\u00e9gionale des landes et marais de Glomel regroupe sur 108 hectares deux sites distants d\u2019une dizaine de kilom\u00e8tres. L\u2019ensemble comprend des Milieux rares et diversifi\u00e9s : landes humides \u00e0 tourbeuses, groupements de tourbi\u00e8res, prairies humides oligotrophes, saulaies boulaies hygrophiles, ch\u00eanaies acidophiles ainsi que quelques m\u00e9gaphorbiaies.","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/18836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=18836"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=18836"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=18836"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=18836"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=18836"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=18836"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=18836"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=18836"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=18836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}