{"id":17291,"date":"2026-05-26T15:23:12","date_gmt":"2026-05-26T13:23:12","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/ecoscop\/"},"modified":"2026-05-26T15:23:12","modified_gmt":"2026-05-26T13:23:12","slug":"ecoscop","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/ecoscop\/","title":{"rendered":"Ecoscop"},"content":{"rendered":"<p>\u00c9coscop est un bureau d\u2019\u00e9tudes technique en environnement, sp\u00e9cialis\u00e9 dans les domaines de l\u2019\u00e9cologie, du paysage, de l\u2019am\u00e9nagement du territoire et de l\u2019urbanisme. L\u2019activit\u00e9 d\u2019\u00c9coscop est centr\u00e9e sur les \u00e9tudes environnementales (\u00e9cologie faune, flore, zones humides). Ces \u00e9tudes s\u2019inscrivent dans le cadre de projets d\u2019am\u00e9nagement avec une prise en compte r\u00e9glementaire de l\u2019environnement : \u00e9tudes d\u2019impact, documents d\u2019urbanisme (PLU, SCOT)\u2026 \u00c9coscop r\u00e9pond \u00e9galement \u00e0 des demandes issues de politiques volontaires (plan de paysage, Gerplan, gestion conservatoire\u2026)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9coscop est un bureau d\u2019\u00e9tudes technique en environnement, sp\u00e9cialis\u00e9 dans les domaines de l\u2019\u00e9cologie, du paysage, de l\u2019am\u00e9nagement du territoire et de l\u2019urbanisme. L\u2019activit\u00e9 d\u2019\u00c9coscop est centr\u00e9e sur les \u00e9tudes environnementales (\u00e9cologie faune, flore, zones humides). Ces \u00e9tudes s\u2019inscrivent dans le cadre de projets d\u2019am\u00e9nagement avec une prise en compte r\u00e9glementaire de l\u2019environnement : \u00e9tudes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[682],"perimetre_intervention":[],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-17291","acteur","type-acteur","status-publish","hentry","type_acteur-entreprises-independants"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ecoscop - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/ecoscop\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ecoscop - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"\u00c9coscop est un bureau d\u2019\u00e9tudes technique en environnement, sp\u00e9cialis\u00e9 dans les domaines de l\u2019\u00e9cologie, du paysage, de l\u2019am\u00e9nagement du territoire et de l\u2019urbanisme. L\u2019activit\u00e9 d\u2019\u00c9coscop est centr\u00e9e sur les \u00e9tudes environnementales (\u00e9cologie faune, flore, zones humides). Ces \u00e9tudes s\u2019inscrivent dans le cadre de projets d\u2019am\u00e9nagement avec une prise en compte r\u00e9glementaire de l\u2019environnement : \u00e9tudes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/ecoscop\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/ecoscop\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/ecoscop\\\/\",\"name\":\"Ecoscop - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-05-26T13:23:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/ecoscop\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/ecoscop\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/ecoscop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ecoscop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ecoscop - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/ecoscop\/","og_locale":"en_US","og_type":"article","og_title":"Ecoscop - A-Igeco","og_description":"\u00c9coscop est un bureau d\u2019\u00e9tudes technique en environnement, sp\u00e9cialis\u00e9 dans les domaines de l\u2019\u00e9cologie, du paysage, de l\u2019am\u00e9nagement du territoire et de l\u2019urbanisme. L\u2019activit\u00e9 d\u2019\u00c9coscop est centr\u00e9e sur les \u00e9tudes environnementales (\u00e9cologie faune, flore, zones humides). Ces \u00e9tudes s\u2019inscrivent dans le cadre de projets d\u2019am\u00e9nagement avec une prise en compte r\u00e9glementaire de l\u2019environnement : \u00e9tudes [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/ecoscop\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/ecoscop\/","url":"https:\/\/a-igeco.fr\/acteurs\/ecoscop\/","name":"Ecoscop - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-05-26T13:23:12+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/ecoscop\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/ecoscop\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/ecoscop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Ecoscop"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00c9coscop est un bureau d\u2019\u00e9tudes technique en environnement, sp\u00e9cialis\u00e9 dans les domaines de l\u2019\u00e9cologie, du paysage, de l\u2019am\u00e9nagement du territoire et de l\u2019urbanisme. L\u2019activit\u00e9 d\u2019\u00c9coscop est centr\u00e9e sur les \u00e9tudes environnementales (\u00e9cologie faune, flore, zones humides). Ces \u00e9tudes s\u2019inscrivent dans le cadre de projets d\u2019am\u00e9nagement avec une prise en compte r\u00e9glementaire de l\u2019environnement : \u00e9tudes&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/17291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=17291"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=17291"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=17291"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=17291"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=17291"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=17291"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=17291"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=17291"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=17291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}