{"id":15750,"date":"2026-04-30T10:51:49","date_gmt":"2026-04-30T08:51:49","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\/"},"modified":"2026-04-30T10:51:49","modified_gmt":"2026-04-30T08:51:49","slug":"biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\/","title":{"rendered":"Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes terrestres \u2014 Universit\u00e9  de Bordeaux"},"content":{"rendered":"<p>Le parcours Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes Terrestres vise \u00e0 renforcer :<\/p>\n<p>les connaissances en \u00e9cologie et \u00e9volution,<br \/>\nl\u2019application de la d\u00e9marche scientifique \u00e0 la r\u00e9solution de probl\u00e9matiques de Sciences,<br \/>\nles comp\u00e9tences d\u2019analyse et la ma\u00eetrise des outils statistiques en biologie-\u00e9cologie,<br \/>\nles comp\u00e9tences d\u2019utilisation des outils mol\u00e9culaires pour l\u2019\u00e9tude des processus \u00e9cologiques et \u00e9volutifs,<br \/>\nles comp\u00e9tences de synth\u00e8se bibliographique,<br \/>\nles capacit\u00e9s r\u00e9dactionnelles et communicationnelles acad\u00e9miques afin de pr\u00e9parer au doctorat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le parcours Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes Terrestres vise \u00e0 renforcer : les connaissances en \u00e9cologie et \u00e9volution, l\u2019application de la d\u00e9marche scientifique \u00e0 la r\u00e9solution de probl\u00e9matiques de Sciences, les comp\u00e9tences d\u2019analyse et la ma\u00eetrise des outils statistiques en biologie-\u00e9cologie, les comp\u00e9tences d\u2019utilisation des outils mol\u00e9culaires pour l\u2019\u00e9tude des processus \u00e9cologiques et \u00e9volutifs, les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[681],"perimetre_intervention":[718],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-15750","acteur","type-acteur","status-publish","hentry","type_acteur-formations","perimetre_intervention-33-gironde"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes terrestres \u2014 Universit\u00e9 de Bordeaux - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes terrestres \u2014 Universit\u00e9 de Bordeaux - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Le parcours Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes Terrestres vise \u00e0 renforcer : les connaissances en \u00e9cologie et \u00e9volution, l\u2019application de la d\u00e9marche scientifique \u00e0 la r\u00e9solution de probl\u00e9matiques de Sciences, les comp\u00e9tences d\u2019analyse et la ma\u00eetrise des outils statistiques en biologie-\u00e9cologie, les comp\u00e9tences d\u2019utilisation des outils mol\u00e9culaires pour l\u2019\u00e9tude des processus \u00e9cologiques et \u00e9volutifs, les [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\\\/\",\"name\":\"Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes terrestres \u2014 Universit\u00e9 de Bordeaux - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-04-30T08:51:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes terrestres \u2014 Universit\u00e9 de Bordeaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes terrestres \u2014 Universit\u00e9 de Bordeaux - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\/","og_locale":"en_US","og_type":"article","og_title":"Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes terrestres \u2014 Universit\u00e9 de Bordeaux - A-Igeco","og_description":"Le parcours Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes Terrestres vise \u00e0 renforcer : les connaissances en \u00e9cologie et \u00e9volution, l\u2019application de la d\u00e9marche scientifique \u00e0 la r\u00e9solution de probl\u00e9matiques de Sciences, les comp\u00e9tences d\u2019analyse et la ma\u00eetrise des outils statistiques en biologie-\u00e9cologie, les comp\u00e9tences d\u2019utilisation des outils mol\u00e9culaires pour l\u2019\u00e9tude des processus \u00e9cologiques et \u00e9volutifs, les [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\/","url":"https:\/\/a-igeco.fr\/acteurs\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\/","name":"Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes terrestres \u2014 Universit\u00e9 de Bordeaux - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-04-30T08:51:49+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/biodiversite-et-fonctionnement-des-ecosystemes-terrestres-universite-de-bordeaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes terrestres \u2014 Universit\u00e9 de Bordeaux"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Le parcours Biodiversit\u00e9 et Fonctionnement des \u00e9cosyst\u00e8mes Terrestres vise \u00e0 renforcer : les connaissances en \u00e9cologie et \u00e9volution, l\u2019application de la d\u00e9marche scientifique \u00e0 la r\u00e9solution de probl\u00e9matiques de Sciences, les comp\u00e9tences d\u2019analyse et la ma\u00eetrise des outils statistiques en biologie-\u00e9cologie, les comp\u00e9tences d\u2019utilisation des outils mol\u00e9culaires pour l\u2019\u00e9tude des processus \u00e9cologiques et \u00e9volutifs, les&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/15750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=15750"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=15750"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=15750"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=15750"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=15750"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=15750"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=15750"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=15750"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=15750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}