{"id":15746,"date":"2026-04-30T10:51:49","date_gmt":"2026-04-30T08:51:49","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\/"},"modified":"2026-04-30T10:51:49","modified_gmt":"2026-04-30T08:51:49","slug":"efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\/","title":{"rendered":"EFCE : Ecologie Fonctionnelle, Comportementale et \u00e9volutive \u2014 Rennes 1"},"content":{"rendered":"<p>Ce parcours vise \u00e0 former des chercheurs, experts ou cadres, sp\u00e9cialis\u00e9s dans le domaine de l\u2019\u00e9cologie et de la gestion de la biodiversit\u00e9 et de l\u2019environnement, capables de s\u2019adapter \u00e0 l\u2019\u00e9volution des besoins en recherche et en expertise dans ce domaine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce parcours vise \u00e0 former des chercheurs, experts ou cadres, sp\u00e9cialis\u00e9s dans le domaine de l\u2019\u00e9cologie et de la gestion de la biodiversit\u00e9 et de l\u2019environnement, capables de s\u2019adapter \u00e0 l\u2019\u00e9volution des besoins en recherche et en expertise dans ce domaine.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[681],"perimetre_intervention":[720],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-15746","acteur","type-acteur","status-publish","hentry","type_acteur-formations","perimetre_intervention-35-ille-et-vilaine"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EFCE : Ecologie Fonctionnelle, Comportementale et \u00e9volutive \u2014 Rennes 1 - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EFCE : Ecologie Fonctionnelle, Comportementale et \u00e9volutive \u2014 Rennes 1 - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Ce parcours vise \u00e0 former des chercheurs, experts ou cadres, sp\u00e9cialis\u00e9s dans le domaine de l\u2019\u00e9cologie et de la gestion de la biodiversit\u00e9 et de l\u2019environnement, capables de s\u2019adapter \u00e0 l\u2019\u00e9volution des besoins en recherche et en expertise dans ce domaine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\\\/\",\"name\":\"EFCE : Ecologie Fonctionnelle, Comportementale et \u00e9volutive \u2014 Rennes 1 - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-04-30T08:51:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EFCE : Ecologie Fonctionnelle, Comportementale et \u00e9volutive \u2014 Rennes 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EFCE : Ecologie Fonctionnelle, Comportementale et \u00e9volutive \u2014 Rennes 1 - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\/","og_locale":"en_US","og_type":"article","og_title":"EFCE : Ecologie Fonctionnelle, Comportementale et \u00e9volutive \u2014 Rennes 1 - A-Igeco","og_description":"Ce parcours vise \u00e0 former des chercheurs, experts ou cadres, sp\u00e9cialis\u00e9s dans le domaine de l\u2019\u00e9cologie et de la gestion de la biodiversit\u00e9 et de l\u2019environnement, capables de s\u2019adapter \u00e0 l\u2019\u00e9volution des besoins en recherche et en expertise dans ce domaine.","og_url":"https:\/\/a-igeco.fr\/acteurs\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\/","url":"https:\/\/a-igeco.fr\/acteurs\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\/","name":"EFCE : Ecologie Fonctionnelle, Comportementale et \u00e9volutive \u2014 Rennes 1 - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-04-30T08:51:49+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/efce-ecologie-fonctionnelle-comportementale-et-evolutive-rennes-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"EFCE : Ecologie Fonctionnelle, Comportementale et \u00e9volutive \u2014 Rennes 1"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Ce parcours vise \u00e0 former des chercheurs, experts ou cadres, sp\u00e9cialis\u00e9s dans le domaine de l\u2019\u00e9cologie et de la gestion de la biodiversit\u00e9 et de l\u2019environnement, capables de s\u2019adapter \u00e0 l\u2019\u00e9volution des besoins en recherche et en expertise dans ce domaine.","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/15746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=15746"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=15746"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=15746"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=15746"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=15746"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=15746"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=15746"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=15746"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=15746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}