{"id":15699,"date":"2026-04-30T10:51:46","date_gmt":"2026-04-30T08:51:46","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\/"},"modified":"2026-04-30T10:51:46","modified_gmt":"2026-04-30T08:51:46","slug":"sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\/","title":{"rendered":"Sciences pour l\u2019environnement \u2013 Gestion de l\u2019environnement et \u00e9cologie littorale \u2014 Universit\u00e9 de La Rochelle"},"content":{"rendered":"<p>Le master Sciences pour l\u2019environnement vous apprend \u00e0 appr\u00e9hender<br \/>\ndes questions complexes de recherche ou de soci\u00e9t\u00e9 relatives \u00e0 la<br \/>\ngestion int\u00e9gr\u00e9e des espaces naturels et littoraux en particulier. Il vous<br \/>\npermet d\u2019acqu\u00e9rir gr\u00e2ce au parcours Gestion de l\u2019Environnement et<br \/>\n\u00c9cologie Littorale (GEEL) des connaissances et comp\u00e9tences sp\u00e9cifiques<br \/>\norient\u00e9es vers la gestion durable des \u00e9cosyst\u00e8mes anthropis\u00e9s. Vous<br \/>\nd\u00e9velopperez \u00e9galement des savoir-\u00eatre utiles dans le monde<br \/>\nprofessionnel et notamment une capacit\u00e9 d\u2019\u00e9coute vis-\u00e0-vis des<br \/>\nsp\u00e9cialistes de disciplines connexes ou compl\u00e9mentaires.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le master Sciences pour l\u2019environnement vous apprend \u00e0 appr\u00e9hender des questions complexes de recherche ou de soci\u00e9t\u00e9 relatives \u00e0 la gestion int\u00e9gr\u00e9e des espaces naturels et littoraux en particulier. Il vous permet d\u2019acqu\u00e9rir gr\u00e2ce au parcours Gestion de l\u2019Environnement et \u00c9cologie Littorale (GEEL) des connaissances et comp\u00e9tences sp\u00e9cifiques orient\u00e9es vers la gestion durable des \u00e9cosyst\u00e8mes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[681],"perimetre_intervention":[701],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-15699","acteur","type-acteur","status-publish","hentry","type_acteur-formations","perimetre_intervention-17-charente-maritime"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sciences pour l\u2019environnement \u2013 Gestion de l\u2019environnement et \u00e9cologie littorale \u2014 Universit\u00e9 de La Rochelle - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sciences pour l\u2019environnement \u2013 Gestion de l\u2019environnement et \u00e9cologie littorale \u2014 Universit\u00e9 de La Rochelle - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Le master Sciences pour l\u2019environnement vous apprend \u00e0 appr\u00e9hender des questions complexes de recherche ou de soci\u00e9t\u00e9 relatives \u00e0 la gestion int\u00e9gr\u00e9e des espaces naturels et littoraux en particulier. Il vous permet d\u2019acqu\u00e9rir gr\u00e2ce au parcours Gestion de l\u2019Environnement et \u00c9cologie Littorale (GEEL) des connaissances et comp\u00e9tences sp\u00e9cifiques orient\u00e9es vers la gestion durable des \u00e9cosyst\u00e8mes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\\\/\",\"name\":\"Sciences pour l\u2019environnement \u2013 Gestion de l\u2019environnement et \u00e9cologie littorale \u2014 Universit\u00e9 de La Rochelle - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-04-30T08:51:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sciences pour l\u2019environnement \u2013 Gestion de l\u2019environnement et \u00e9cologie littorale \u2014 Universit\u00e9 de La Rochelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sciences pour l\u2019environnement \u2013 Gestion de l\u2019environnement et \u00e9cologie littorale \u2014 Universit\u00e9 de La Rochelle - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\/","og_locale":"en_US","og_type":"article","og_title":"Sciences pour l\u2019environnement \u2013 Gestion de l\u2019environnement et \u00e9cologie littorale \u2014 Universit\u00e9 de La Rochelle - A-Igeco","og_description":"Le master Sciences pour l\u2019environnement vous apprend \u00e0 appr\u00e9hender des questions complexes de recherche ou de soci\u00e9t\u00e9 relatives \u00e0 la gestion int\u00e9gr\u00e9e des espaces naturels et littoraux en particulier. Il vous permet d\u2019acqu\u00e9rir gr\u00e2ce au parcours Gestion de l\u2019Environnement et \u00c9cologie Littorale (GEEL) des connaissances et comp\u00e9tences sp\u00e9cifiques orient\u00e9es vers la gestion durable des \u00e9cosyst\u00e8mes [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\/","url":"https:\/\/a-igeco.fr\/acteurs\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\/","name":"Sciences pour l\u2019environnement \u2013 Gestion de l\u2019environnement et \u00e9cologie littorale \u2014 Universit\u00e9 de La Rochelle - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-04-30T08:51:46+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/sciences-pour-lenvironnement-gestion-de-lenvironnement-et-ecologie-littorale-universite-de-la-rochelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Sciences pour l\u2019environnement \u2013 Gestion de l\u2019environnement et \u00e9cologie littorale \u2014 Universit\u00e9 de La Rochelle"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Le master Sciences pour l\u2019environnement vous apprend \u00e0 appr\u00e9hender des questions complexes de recherche ou de soci\u00e9t\u00e9 relatives \u00e0 la gestion int\u00e9gr\u00e9e des espaces naturels et littoraux en particulier. Il vous permet d\u2019acqu\u00e9rir gr\u00e2ce au parcours Gestion de l\u2019Environnement et \u00c9cologie Littorale (GEEL) des connaissances et comp\u00e9tences sp\u00e9cifiques orient\u00e9es vers la gestion durable des \u00e9cosyst\u00e8mes&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/15699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=15699"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=15699"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=15699"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=15699"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=15699"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=15699"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=15699"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=15699"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=15699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}