{"id":15651,"date":"2026-04-30T10:51:43","date_gmt":"2026-04-30T08:51:43","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\/"},"modified":"2026-04-30T10:51:43","modified_gmt":"2026-04-30T08:51:43","slug":"metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\/","title":{"rendered":"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013\nRestauration Ecologique des Milieux Aquatiques (REMA) \u2014 CFPH Lyon-Ecully"},"content":{"rendered":"<p>Former par alternance des assistant.e.s-ing\u00e9nieur.e.s et charg\u00e9.e.s de<br \/>\nmission aptes \u00e0 superviser des chantiers de restauration \u00e9cologique des<br \/>\nmilieux aquatiques<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Former par alternance des assistant.e.s-ing\u00e9nieur.e.s et charg\u00e9.e.s de mission aptes \u00e0 superviser des chantiers de restauration \u00e9cologique des milieux aquatiques<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[681],"perimetre_intervention":[754],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-15651","acteur","type-acteur","status-publish","hentry","type_acteur-formations","perimetre_intervention-69-rhone"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Restauration Ecologique des Milieux Aquatiques (REMA) \u2014 CFPH Lyon-Ecully - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Restauration Ecologique des Milieux Aquatiques (REMA) \u2014 CFPH Lyon-Ecully - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Former par alternance des assistant.e.s-ing\u00e9nieur.e.s et charg\u00e9.e.s de mission aptes \u00e0 superviser des chantiers de restauration \u00e9cologique des milieux aquatiques\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\\\/\",\"name\":\"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Restauration Ecologique des Milieux Aquatiques (REMA) \u2014 CFPH Lyon-Ecully - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-04-30T08:51:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Restauration Ecologique des Milieux Aquatiques (REMA) \u2014 CFPH Lyon-Ecully\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Restauration Ecologique des Milieux Aquatiques (REMA) \u2014 CFPH Lyon-Ecully - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\/","og_locale":"en_US","og_type":"article","og_title":"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Restauration Ecologique des Milieux Aquatiques (REMA) \u2014 CFPH Lyon-Ecully - A-Igeco","og_description":"Former par alternance des assistant.e.s-ing\u00e9nieur.e.s et charg\u00e9.e.s de mission aptes \u00e0 superviser des chantiers de restauration \u00e9cologique des milieux aquatiques","og_url":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\/","url":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\/","name":"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Restauration Ecologique des Milieux Aquatiques (REMA) \u2014 CFPH Lyon-Ecully - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-04-30T08:51:43+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-restauration-ecologique-des-milieux-aquatiques-rema-cfph-lyon-ecully\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Restauration Ecologique des Milieux Aquatiques (REMA) \u2014 CFPH Lyon-Ecully"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Former par alternance des assistant.e.s-ing\u00e9nieur.e.s et charg\u00e9.e.s de mission aptes \u00e0 superviser des chantiers de restauration \u00e9cologique des milieux aquatiques","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/15651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=15651"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=15651"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=15651"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=15651"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=15651"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=15651"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=15651"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=15651"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=15651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}