{"id":15650,"date":"2026-04-30T10:51:43","date_gmt":"2026-04-30T08:51:43","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\/"},"modified":"2026-04-30T10:51:43","modified_gmt":"2026-04-30T08:51:43","slug":"metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\/","title":{"rendered":"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Environnement Marin, Ressources et Gestion \u2014 Universit\u00e9 de Littoral Cot\u00e9 d&#8217;Opale"},"content":{"rendered":"<p>Former des professionnels dans les domaines de l\u2019aquariologie, de<br \/>\nl\u2019aquaculture, de la valorisation et de la vulgarisation. Concourir \u00e0 la<br \/>\npr\u00e9servation et la connaissance des \u00e9cosyst\u00e8mes, la sauvegarde et la<br \/>\nr\u00e9introduction d\u2019esp\u00e8ces dans les milieux impact\u00e9s par les activit\u00e9s<br \/>\nhumaines. D\u00e9velopper les modalit\u00e9s de reproduction des esp\u00e8ces<br \/>\nmenac\u00e9es, participer \u00e0 la collecte et aux \u00e9changes de donn\u00e9es entre les<br \/>\n\u00e9tablissements pour am\u00e9liorer les techniques de pr\u00e9servations et de<br \/>\nreproduction. Communiquer, vulgariser \u00e0 travers des congr\u00e8s, des<br \/>\nassociations nationales et europ\u00e9ennes, le grand public notamment en<br \/>\nlangue anglaise.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Former des professionnels dans les domaines de l\u2019aquariologie, de l\u2019aquaculture, de la valorisation et de la vulgarisation. Concourir \u00e0 la pr\u00e9servation et la connaissance des \u00e9cosyst\u00e8mes, la sauvegarde et la r\u00e9introduction d\u2019esp\u00e8ces dans les milieux impact\u00e9s par les activit\u00e9s humaines. D\u00e9velopper les modalit\u00e9s de reproduction des esp\u00e8ces menac\u00e9es, participer \u00e0 la collecte et aux \u00e9changes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[681],"perimetre_intervention":[747],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-15650","acteur","type-acteur","status-publish","hentry","type_acteur-formations","perimetre_intervention-62-pas-de-calais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Environnement Marin, Ressources et Gestion \u2014 Universit\u00e9 de Littoral Cot\u00e9 d&#039;Opale - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Environnement Marin, Ressources et Gestion \u2014 Universit\u00e9 de Littoral Cot\u00e9 d&#039;Opale - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Former des professionnels dans les domaines de l\u2019aquariologie, de l\u2019aquaculture, de la valorisation et de la vulgarisation. Concourir \u00e0 la pr\u00e9servation et la connaissance des \u00e9cosyst\u00e8mes, la sauvegarde et la r\u00e9introduction d\u2019esp\u00e8ces dans les milieux impact\u00e9s par les activit\u00e9s humaines. D\u00e9velopper les modalit\u00e9s de reproduction des esp\u00e8ces menac\u00e9es, participer \u00e0 la collecte et aux \u00e9changes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\\\/\",\"name\":\"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Environnement Marin, Ressources et Gestion \u2014 Universit\u00e9 de Littoral Cot\u00e9 d'Opale - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-04-30T08:51:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Environnement Marin, Ressources et Gestion \u2014 Universit\u00e9 de Littoral Cot\u00e9 d&rsquo;Opale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Environnement Marin, Ressources et Gestion \u2014 Universit\u00e9 de Littoral Cot\u00e9 d'Opale - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\/","og_locale":"en_US","og_type":"article","og_title":"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Environnement Marin, Ressources et Gestion \u2014 Universit\u00e9 de Littoral Cot\u00e9 d'Opale - A-Igeco","og_description":"Former des professionnels dans les domaines de l\u2019aquariologie, de l\u2019aquaculture, de la valorisation et de la vulgarisation. Concourir \u00e0 la pr\u00e9servation et la connaissance des \u00e9cosyst\u00e8mes, la sauvegarde et la r\u00e9introduction d\u2019esp\u00e8ces dans les milieux impact\u00e9s par les activit\u00e9s humaines. D\u00e9velopper les modalit\u00e9s de reproduction des esp\u00e8ces menac\u00e9es, participer \u00e0 la collecte et aux \u00e9changes [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\/","url":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\/","name":"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Environnement Marin, Ressources et Gestion \u2014 Universit\u00e9 de Littoral Cot\u00e9 d'Opale - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-04-30T08:51:43+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/metiers-de-la-protection-et-de-la-gestion-de-lenvironnement-environnement-marin-ressources-et-gestion-universite-de-littoral-cote-dopale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"M\u00e9tiers de la protection et de la gestion de l\u2019environnement \u2013 Environnement Marin, Ressources et Gestion \u2014 Universit\u00e9 de Littoral Cot\u00e9 d&rsquo;Opale"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Former des professionnels dans les domaines de l\u2019aquariologie, de l\u2019aquaculture, de la valorisation et de la vulgarisation. Concourir \u00e0 la pr\u00e9servation et la connaissance des \u00e9cosyst\u00e8mes, la sauvegarde et la r\u00e9introduction d\u2019esp\u00e8ces dans les milieux impact\u00e9s par les activit\u00e9s humaines. D\u00e9velopper les modalit\u00e9s de reproduction des esp\u00e8ces menac\u00e9es, participer \u00e0 la collecte et aux \u00e9changes&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/15650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=15650"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=15650"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=15650"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=15650"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=15650"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=15650"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=15650"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=15650"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=15650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}