{"id":15626,"date":"2026-04-30T10:51:42","date_gmt":"2026-04-30T08:51:42","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\/"},"modified":"2026-04-30T10:51:42","modified_gmt":"2026-04-30T08:51:42","slug":"licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\/","title":{"rendered":"Licence pro MAEP : milieux aquatiques et eaux pluviales \u2014 Lyc\u00e9e Agrotec de Seyssuel"},"content":{"rendered":"<p>Les objectifs vis\u00e9sLicence pro MAEP<br \/>\nMa\u00eetriser les outils du diagnostic de l\u2019\u00e9tat et de l\u2019\u00e9volution des \u00e9cosyst\u00e8mes.<br \/>\nAppliquer les syst\u00e8mes d\u2019information g\u00e9ographiques et les outils informatiques de g\u00e9olocalisation.<br \/>\nMa\u00eetriser les outils l\u00e9gislatifs et en accord avec la r\u00e9glementation li\u00e9s \u00e0 la protection des espaces naturels.<br \/>\nConna\u00eetre les acteurs et les enjeux de la gestion des espaces naturels.<br \/>\nAssurer le suivi terrain des actions de protection des milieux.<br \/>\nMa\u00eetriser les techniques de traitement et de gestion des eaux pluviales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les objectifs vis\u00e9sLicence pro MAEP Ma\u00eetriser les outils du diagnostic de l\u2019\u00e9tat et de l\u2019\u00e9volution des \u00e9cosyst\u00e8mes. Appliquer les syst\u00e8mes d\u2019information g\u00e9ographiques et les outils informatiques de g\u00e9olocalisation. Ma\u00eetriser les outils l\u00e9gislatifs et en accord avec la r\u00e9glementation li\u00e9s \u00e0 la protection des espaces naturels. Conna\u00eetre les acteurs et les enjeux de la gestion des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[681],"perimetre_intervention":[723],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-15626","acteur","type-acteur","status-publish","hentry","type_acteur-formations","perimetre_intervention-38-isere"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Licence pro MAEP : milieux aquatiques et eaux pluviales \u2014 Lyc\u00e9e Agrotec de Seyssuel - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Licence pro MAEP : milieux aquatiques et eaux pluviales \u2014 Lyc\u00e9e Agrotec de Seyssuel - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Les objectifs vis\u00e9sLicence pro MAEP Ma\u00eetriser les outils du diagnostic de l\u2019\u00e9tat et de l\u2019\u00e9volution des \u00e9cosyst\u00e8mes. Appliquer les syst\u00e8mes d\u2019information g\u00e9ographiques et les outils informatiques de g\u00e9olocalisation. Ma\u00eetriser les outils l\u00e9gislatifs et en accord avec la r\u00e9glementation li\u00e9s \u00e0 la protection des espaces naturels. Conna\u00eetre les acteurs et les enjeux de la gestion des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\\\/\",\"name\":\"Licence pro MAEP : milieux aquatiques et eaux pluviales \u2014 Lyc\u00e9e Agrotec de Seyssuel - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-04-30T08:51:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Licence pro MAEP : milieux aquatiques et eaux pluviales \u2014 Lyc\u00e9e Agrotec de Seyssuel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Licence pro MAEP : milieux aquatiques et eaux pluviales \u2014 Lyc\u00e9e Agrotec de Seyssuel - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\/","og_locale":"en_US","og_type":"article","og_title":"Licence pro MAEP : milieux aquatiques et eaux pluviales \u2014 Lyc\u00e9e Agrotec de Seyssuel - A-Igeco","og_description":"Les objectifs vis\u00e9sLicence pro MAEP Ma\u00eetriser les outils du diagnostic de l\u2019\u00e9tat et de l\u2019\u00e9volution des \u00e9cosyst\u00e8mes. Appliquer les syst\u00e8mes d\u2019information g\u00e9ographiques et les outils informatiques de g\u00e9olocalisation. Ma\u00eetriser les outils l\u00e9gislatifs et en accord avec la r\u00e9glementation li\u00e9s \u00e0 la protection des espaces naturels. Conna\u00eetre les acteurs et les enjeux de la gestion des [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\/","url":"https:\/\/a-igeco.fr\/acteurs\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\/","name":"Licence pro MAEP : milieux aquatiques et eaux pluviales \u2014 Lyc\u00e9e Agrotec de Seyssuel - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-04-30T08:51:42+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/licence-pro-maep-milieux-aquatiques-et-eaux-pluviales-lycee-agrotec-de-seyssuel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Licence pro MAEP : milieux aquatiques et eaux pluviales \u2014 Lyc\u00e9e Agrotec de Seyssuel"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Les objectifs vis\u00e9sLicence pro MAEP Ma\u00eetriser les outils du diagnostic de l\u2019\u00e9tat et de l\u2019\u00e9volution des \u00e9cosyst\u00e8mes. Appliquer les syst\u00e8mes d\u2019information g\u00e9ographiques et les outils informatiques de g\u00e9olocalisation. Ma\u00eetriser les outils l\u00e9gislatifs et en accord avec la r\u00e9glementation li\u00e9s \u00e0 la protection des espaces naturels. Conna\u00eetre les acteurs et les enjeux de la gestion des&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/15626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=15626"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=15626"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=15626"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=15626"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=15626"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=15626"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=15626"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=15626"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=15626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}