{"id":15537,"date":"2026-04-30T10:51:37","date_gmt":"2026-04-30T08:51:37","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-lycee-nature\/"},"modified":"2026-04-30T10:51:37","modified_gmt":"2026-04-30T08:51:37","slug":"gestion-et-protection-de-la-nature-lycee-nature","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/gestion-et-protection-de-la-nature-lycee-nature\/","title":{"rendered":"Gestion et Protection de la Nature \u2014 Lyc\u00e9e Nature"},"content":{"rendered":"<p>Ces professionnels participent \u00e0 des projets de gestion et de<br \/>\nvalorisation des espaces naturels, de pr\u00e9servation ou de restauration<br \/>\ndes richesses \u00e9cologiques et de la biodiversit\u00e9 en lien avec les activit\u00e9s<br \/>\nhumaines. Ce professionnel intervient \u00e9galement pour mettre en<br \/>\nvaleur les espaces, sensibiliser et \u00e9duquer les publics (animation<br \/>\nnature, \u00e9ducation \u00e0 l\u2019environnement). Les employeurs potentiels sont<br \/>\nles associations de protection de la nature, les conservatoires d&#8217;espaces<br \/>\nnaturels, les centres permanents d&#8217;initiatives pour l&#8217;environnement, les<br \/>\nf\u00e9d\u00e9rations d&#8217;usagers (chasse, p\u00eache &#8230;) , les entreprises de gestion et<br \/>\nd&#8217;entretien des espaces naturels, les bureaux d&#8217;\u00e9tude, les<br \/>\n\u00e9tablissements publics depuis les parcs jusqu&#8217;aux collectivit\u00e9s<br \/>\nterritoriales en passant par les organismes sp\u00e9cialis\u00e9s (Office Fran\u00e7ais<br \/>\nde la Biodiversit\u00e9, Conservatoire du littoral &#8230;), les organismes de<br \/>\nd\u00e9veloppement agricole, etc. Ce BTS GPN permet d&#8217;envisager des<br \/>\npoursuites d&#8217;\u00e9tudes sup\u00e9rieures : licences professionnelles, parcours<br \/>\nuniversitaires, \u00e9coles agronomiques, etc. Ces poursuites sont d&#8217;aille<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ces professionnels participent \u00e0 des projets de gestion et de valorisation des espaces naturels, de pr\u00e9servation ou de restauration des richesses \u00e9cologiques et de la biodiversit\u00e9 en lien avec les activit\u00e9s humaines. Ce professionnel intervient \u00e9galement pour mettre en valeur les espaces, sensibiliser et \u00e9duquer les publics (animation nature, \u00e9ducation \u00e0 l\u2019environnement). Les employeurs potentiels [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[681],"perimetre_intervention":[770],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-15537","acteur","type-acteur","status-publish","hentry","type_acteur-formations","perimetre_intervention-85-vendee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gestion et Protection de la Nature \u2014 Lyc\u00e9e Nature - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-lycee-nature\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gestion et Protection de la Nature \u2014 Lyc\u00e9e Nature - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Ces professionnels participent \u00e0 des projets de gestion et de valorisation des espaces naturels, de pr\u00e9servation ou de restauration des richesses \u00e9cologiques et de la biodiversit\u00e9 en lien avec les activit\u00e9s humaines. Ce professionnel intervient \u00e9galement pour mettre en valeur les espaces, sensibiliser et \u00e9duquer les publics (animation nature, \u00e9ducation \u00e0 l\u2019environnement). Les employeurs potentiels [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-lycee-nature\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/gestion-et-protection-de-la-nature-lycee-nature\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/gestion-et-protection-de-la-nature-lycee-nature\\\/\",\"name\":\"Gestion et Protection de la Nature \u2014 Lyc\u00e9e Nature - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-04-30T08:51:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/gestion-et-protection-de-la-nature-lycee-nature\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/gestion-et-protection-de-la-nature-lycee-nature\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/gestion-et-protection-de-la-nature-lycee-nature\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gestion et Protection de la Nature \u2014 Lyc\u00e9e Nature\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gestion et Protection de la Nature \u2014 Lyc\u00e9e Nature - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-lycee-nature\/","og_locale":"en_US","og_type":"article","og_title":"Gestion et Protection de la Nature \u2014 Lyc\u00e9e Nature - A-Igeco","og_description":"Ces professionnels participent \u00e0 des projets de gestion et de valorisation des espaces naturels, de pr\u00e9servation ou de restauration des richesses \u00e9cologiques et de la biodiversit\u00e9 en lien avec les activit\u00e9s humaines. Ce professionnel intervient \u00e9galement pour mettre en valeur les espaces, sensibiliser et \u00e9duquer les publics (animation nature, \u00e9ducation \u00e0 l\u2019environnement). Les employeurs potentiels [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-lycee-nature\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-lycee-nature\/","url":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-lycee-nature\/","name":"Gestion et Protection de la Nature \u2014 Lyc\u00e9e Nature - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-04-30T08:51:37+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-lycee-nature\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-lycee-nature\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-lycee-nature\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Gestion et Protection de la Nature \u2014 Lyc\u00e9e Nature"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Ces professionnels participent \u00e0 des projets de gestion et de valorisation des espaces naturels, de pr\u00e9servation ou de restauration des richesses \u00e9cologiques et de la biodiversit\u00e9 en lien avec les activit\u00e9s humaines. Ce professionnel intervient \u00e9galement pour mettre en valeur les espaces, sensibiliser et \u00e9duquer les publics (animation nature, \u00e9ducation \u00e0 l\u2019environnement). Les employeurs potentiels&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/15537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=15537"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=15537"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=15537"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=15537"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=15537"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=15537"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=15537"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=15537"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=15537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}