{"id":15521,"date":"2026-04-30T10:51:36","date_gmt":"2026-04-30T08:51:36","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\/"},"modified":"2026-04-30T10:51:36","modified_gmt":"2026-04-30T08:51:36","slug":"gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\/","title":{"rendered":"Gestion et Protection de la Nature \u2014 CFPPA La C\u00f4te St Andr\u00e9"},"content":{"rendered":"<p>Le technicien sup\u00e9rieur en Gestion et Protection de la Nature met en<br \/>\n\u0153uvre un projet de gestion des espaces naturels et d&#8217;animation des<br \/>\npublics, assure les diagnostics d\u2019un espace de nature, propose et met<br \/>\nen place les solutions techniques de gestion et participe au<br \/>\nd\u00e9veloppement local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le technicien sup\u00e9rieur en Gestion et Protection de la Nature met en \u0153uvre un projet de gestion des espaces naturels et d&#8217;animation des publics, assure les diagnostics d\u2019un espace de nature, propose et met en place les solutions techniques de gestion et participe au d\u00e9veloppement local.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[681],"perimetre_intervention":[723],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-15521","acteur","type-acteur","status-publish","hentry","type_acteur-formations","perimetre_intervention-38-isere"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gestion et Protection de la Nature \u2014 CFPPA La C\u00f4te St Andr\u00e9 - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gestion et Protection de la Nature \u2014 CFPPA La C\u00f4te St Andr\u00e9 - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Le technicien sup\u00e9rieur en Gestion et Protection de la Nature met en \u0153uvre un projet de gestion des espaces naturels et d&#8217;animation des publics, assure les diagnostics d\u2019un espace de nature, propose et met en place les solutions techniques de gestion et participe au d\u00e9veloppement local.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\\\/\",\"name\":\"Gestion et Protection de la Nature \u2014 CFPPA La C\u00f4te St Andr\u00e9 - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-04-30T08:51:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gestion et Protection de la Nature \u2014 CFPPA La C\u00f4te St Andr\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gestion et Protection de la Nature \u2014 CFPPA La C\u00f4te St Andr\u00e9 - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\/","og_locale":"en_US","og_type":"article","og_title":"Gestion et Protection de la Nature \u2014 CFPPA La C\u00f4te St Andr\u00e9 - A-Igeco","og_description":"Le technicien sup\u00e9rieur en Gestion et Protection de la Nature met en \u0153uvre un projet de gestion des espaces naturels et d&#8217;animation des publics, assure les diagnostics d\u2019un espace de nature, propose et met en place les solutions techniques de gestion et participe au d\u00e9veloppement local.","og_url":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\/","url":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\/","name":"Gestion et Protection de la Nature \u2014 CFPPA La C\u00f4te St Andr\u00e9 - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-04-30T08:51:36+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/gestion-et-protection-de-la-nature-cfppa-la-cote-st-andre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Gestion et Protection de la Nature \u2014 CFPPA La C\u00f4te St Andr\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Le technicien sup\u00e9rieur en Gestion et Protection de la Nature met en \u0153uvre un projet de gestion des espaces naturels et d&#8217;animation des publics, assure les diagnostics d\u2019un espace de nature, propose et met en place les solutions techniques de gestion et participe au d\u00e9veloppement local.","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/15521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=15521"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=15521"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=15521"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=15521"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=15521"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=15521"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=15521"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=15521"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=15521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}