{"id":15503,"date":"2026-04-30T10:51:35","date_gmt":"2026-04-30T08:51:35","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/expertise-naturaliste-des-milieux-pole-sup-nature\/"},"modified":"2026-04-30T10:51:35","modified_gmt":"2026-04-30T08:51:35","slug":"expertise-naturaliste-des-milieux-pole-sup-nature","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/expertise-naturaliste-des-milieux-pole-sup-nature\/","title":{"rendered":"Expertise naturaliste des milieux \u2014 Pole Sup Nature"},"content":{"rendered":"<p>La nouveaut\u00e9 de cette formation est qu\u2019elle offre des comp\u00e9tences<br \/>\ndans le domaine de l\u2019\u00e9tude et de la gestion des milieux tropicaux ou des<br \/>\nmilieux marins, permettant d\u2019acc\u00e9der \u00e0 des d\u00e9bouch\u00e9s professionnels<br \/>\ndans le monde entier ! Elle est centr\u00e9e vers l\u2019acquisition de<br \/>\ncomp\u00e9tences naturalistes (habitat, faune, flore), de connaissances des<br \/>\nm\u00e9thodes et outils d\u2019inventaires et de suivis, des connaissances des<br \/>\nmesures de gestion adapt\u00e9es aux \u00e9cosyst\u00e8mes et de la r\u00e8glementation<br \/>\nrelative en vigueur. Deux sp\u00e9cialit\u00e9s sont propos\u00e9es et permettent de<br \/>\ncompl\u00e9ter le socle de base qui est centr\u00e9 sur les \u00e9cosyst\u00e8mes<br \/>\ncontinentaux de zone pal\u00e9arctique, se concentrant particuli\u00e8rement<br \/>\nsur l\u2019Europe : \u00e9cosyst\u00e8mes marins ou \u00e9cosyst\u00e8mes tropicaux. Le choix<br \/>\nd\u2019une sp\u00e9cialit\u00e9 de formation est obligatoire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nouveaut\u00e9 de cette formation est qu\u2019elle offre des comp\u00e9tences dans le domaine de l\u2019\u00e9tude et de la gestion des milieux tropicaux ou des milieux marins, permettant d\u2019acc\u00e9der \u00e0 des d\u00e9bouch\u00e9s professionnels dans le monde entier ! Elle est centr\u00e9e vers l\u2019acquisition de comp\u00e9tences naturalistes (habitat, faune, flore), de connaissances des m\u00e9thodes et outils d\u2019inventaires [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[681],"perimetre_intervention":[719],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[],"class_list":["post-15503","acteur","type-acteur","status-publish","hentry","type_acteur-formations","perimetre_intervention-34-herault"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Expertise naturaliste des milieux \u2014 Pole Sup Nature - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/expertise-naturaliste-des-milieux-pole-sup-nature\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expertise naturaliste des milieux \u2014 Pole Sup Nature - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"La nouveaut\u00e9 de cette formation est qu\u2019elle offre des comp\u00e9tences dans le domaine de l\u2019\u00e9tude et de la gestion des milieux tropicaux ou des milieux marins, permettant d\u2019acc\u00e9der \u00e0 des d\u00e9bouch\u00e9s professionnels dans le monde entier ! Elle est centr\u00e9e vers l\u2019acquisition de comp\u00e9tences naturalistes (habitat, faune, flore), de connaissances des m\u00e9thodes et outils d\u2019inventaires [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/expertise-naturaliste-des-milieux-pole-sup-nature\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/expertise-naturaliste-des-milieux-pole-sup-nature\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/expertise-naturaliste-des-milieux-pole-sup-nature\\\/\",\"name\":\"Expertise naturaliste des milieux \u2014 Pole Sup Nature - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-04-30T08:51:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/expertise-naturaliste-des-milieux-pole-sup-nature\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/expertise-naturaliste-des-milieux-pole-sup-nature\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/expertise-naturaliste-des-milieux-pole-sup-nature\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Expertise naturaliste des milieux \u2014 Pole Sup Nature\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expertise naturaliste des milieux \u2014 Pole Sup Nature - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/expertise-naturaliste-des-milieux-pole-sup-nature\/","og_locale":"en_US","og_type":"article","og_title":"Expertise naturaliste des milieux \u2014 Pole Sup Nature - A-Igeco","og_description":"La nouveaut\u00e9 de cette formation est qu\u2019elle offre des comp\u00e9tences dans le domaine de l\u2019\u00e9tude et de la gestion des milieux tropicaux ou des milieux marins, permettant d\u2019acc\u00e9der \u00e0 des d\u00e9bouch\u00e9s professionnels dans le monde entier ! Elle est centr\u00e9e vers l\u2019acquisition de comp\u00e9tences naturalistes (habitat, faune, flore), de connaissances des m\u00e9thodes et outils d\u2019inventaires [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/expertise-naturaliste-des-milieux-pole-sup-nature\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/expertise-naturaliste-des-milieux-pole-sup-nature\/","url":"https:\/\/a-igeco.fr\/acteurs\/expertise-naturaliste-des-milieux-pole-sup-nature\/","name":"Expertise naturaliste des milieux \u2014 Pole Sup Nature - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-04-30T08:51:35+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/expertise-naturaliste-des-milieux-pole-sup-nature\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/expertise-naturaliste-des-milieux-pole-sup-nature\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/expertise-naturaliste-des-milieux-pole-sup-nature\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"Expertise naturaliste des milieux \u2014 Pole Sup Nature"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"La nouveaut\u00e9 de cette formation est qu\u2019elle offre des comp\u00e9tences dans le domaine de l\u2019\u00e9tude et de la gestion des milieux tropicaux ou des milieux marins, permettant d\u2019acc\u00e9der \u00e0 des d\u00e9bouch\u00e9s professionnels dans le monde entier ! Elle est centr\u00e9e vers l\u2019acquisition de comp\u00e9tences naturalistes (habitat, faune, flore), de connaissances des m\u00e9thodes et outils d\u2019inventaires&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/15503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=15503"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=15503"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=15503"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=15503"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=15503"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=15503"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=15503"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=15503"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=15503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}