{"id":15286,"date":"2026-04-28T12:57:32","date_gmt":"2026-04-28T10:57:32","guid":{"rendered":"https:\/\/a-igeco.fr\/acteurs\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\/"},"modified":"2026-04-28T12:57:32","modified_gmt":"2026-04-28T10:57:32","slug":"ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys","status":"publish","type":"acteur","link":"https:\/\/a-igeco.fr\/en\/acteurs\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\/","title":{"rendered":"\u00c9cologie fonctionnelle et \u00e9cotoxicologie des agro\u00e9cosyst\u00e8mes  EcoSys"},"content":{"rendered":"<p>Les travaux de l\u2019UMR\u00a0visent \u00e0 traiter d\u2019une mani\u00e8re int\u00e9gr\u00e9e le fonctionnement des agro\u00e9cosyst\u00e8mes et leurs relations avec l\u2019environnement. Ce fonctionnement est appr\u00e9hend\u00e9 en particulier \u00e0 partir des concepts de l\u2019\u00e9cologie fonctionnelle et de l\u2019\u00e9cotoxicologie, prenant en compte les flux de mati\u00e8re et d\u2019\u00e9nergie et les fonctions des organismes isol\u00e9s ou en interaction avec leur milieu \u00e0 divers niveaux d\u2019organisation spatiale (local, r\u00e9gional, national). Les travaux de l\u2019unit\u00e9 s\u2019organisent autour de la notion de services \u00e9cosyst\u00e9miques avec l\u2018objectif de quantifier exp\u00e9rimentalement et pr\u00e9dire par mod\u00e9lisation les performances agronomiques, environnementales et sanitaires des agrosyst\u00e8mes sous contrainte des changements globaux (climat, changement d\u2019usage des sols et des pratiques,\u00a0pollution).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les travaux de l\u2019UMR\u00a0visent \u00e0 traiter d\u2019une mani\u00e8re int\u00e9gr\u00e9e le fonctionnement des agro\u00e9cosyst\u00e8mes et leurs relations avec l\u2019environnement. Ce fonctionnement est appr\u00e9hend\u00e9 en particulier \u00e0 partir des concepts de l\u2019\u00e9cologie fonctionnelle et de l\u2019\u00e9cotoxicologie, prenant en compte les flux de mati\u00e8re et d\u2019\u00e9nergie et les fonctions des organismes isol\u00e9s ou en interaction avec leur milieu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","type_acteur":[680],"perimetre_intervention":[],"milieux_intervention":[],"domaine_activite":[],"thematique":[],"recherche_umr":[],"recherche_centre":[],"recherche_universite":[891],"class_list":["post-15286","acteur","type-acteur","status-publish","hentry","type_acteur-recherche","recherche_universite-agroparistech-universite-paris-saclay"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9cologie fonctionnelle et \u00e9cotoxicologie des agro\u00e9cosyst\u00e8mes EcoSys - A-Igeco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a-igeco.fr\/acteurs\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9cologie fonctionnelle et \u00e9cotoxicologie des agro\u00e9cosyst\u00e8mes EcoSys - A-Igeco\" \/>\n<meta property=\"og:description\" content=\"Les travaux de l\u2019UMR\u00a0visent \u00e0 traiter d\u2019une mani\u00e8re int\u00e9gr\u00e9e le fonctionnement des agro\u00e9cosyst\u00e8mes et leurs relations avec l\u2019environnement. Ce fonctionnement est appr\u00e9hend\u00e9 en particulier \u00e0 partir des concepts de l\u2019\u00e9cologie fonctionnelle et de l\u2019\u00e9cotoxicologie, prenant en compte les flux de mati\u00e8re et d\u2019\u00e9nergie et les fonctions des organismes isol\u00e9s ou en interaction avec leur milieu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a-igeco.fr\/acteurs\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Igeco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\\\/\",\"name\":\"\u00c9cologie fonctionnelle et \u00e9cotoxicologie des agro\u00e9cosyst\u00e8mes EcoSys - A-Igeco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\"},\"datePublished\":\"2026-04-28T10:57:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/en\\\/federer-les-reseaux-des-professionnels-de-la-biodiversite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acteurs\",\"item\":\"https:\\\/\\\/a-igeco.fr\\\/acteurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9cologie fonctionnelle et \u00e9cotoxicologie des agro\u00e9cosyst\u00e8mes EcoSys\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#website\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"name\":\"A-Igeco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a-igeco.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#organization\",\"name\":\"A-Igeco\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"contentUrl\":\"https:\\\/\\\/a-igeco.fr\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Logo_A-IGEco_blanc.png\",\"width\":1841,\"height\":678,\"caption\":\"A-Igeco\"},\"image\":{\"@id\":\"https:\\\/\\\/a-igeco.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9cologie fonctionnelle et \u00e9cotoxicologie des agro\u00e9cosyst\u00e8mes EcoSys - A-Igeco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a-igeco.fr\/acteurs\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\/","og_locale":"en_US","og_type":"article","og_title":"\u00c9cologie fonctionnelle et \u00e9cotoxicologie des agro\u00e9cosyst\u00e8mes EcoSys - A-Igeco","og_description":"Les travaux de l\u2019UMR\u00a0visent \u00e0 traiter d\u2019une mani\u00e8re int\u00e9gr\u00e9e le fonctionnement des agro\u00e9cosyst\u00e8mes et leurs relations avec l\u2019environnement. Ce fonctionnement est appr\u00e9hend\u00e9 en particulier \u00e0 partir des concepts de l\u2019\u00e9cologie fonctionnelle et de l\u2019\u00e9cotoxicologie, prenant en compte les flux de mati\u00e8re et d\u2019\u00e9nergie et les fonctions des organismes isol\u00e9s ou en interaction avec leur milieu [&hellip;]","og_url":"https:\/\/a-igeco.fr\/acteurs\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\/","og_site_name":"A-Igeco","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a-igeco.fr\/acteurs\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\/","url":"https:\/\/a-igeco.fr\/acteurs\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\/","name":"\u00c9cologie fonctionnelle et \u00e9cotoxicologie des agro\u00e9cosyst\u00e8mes EcoSys - A-Igeco","isPartOf":{"@id":"https:\/\/a-igeco.fr\/#website"},"datePublished":"2026-04-28T10:57:32+00:00","breadcrumb":{"@id":"https:\/\/a-igeco.fr\/acteurs\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a-igeco.fr\/acteurs\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a-igeco.fr\/acteurs\/ecologie-fonctionnelle-et-ecotoxicologie-des-agroecosystemes-ecosys\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/a-igeco.fr\/en\/federer-les-reseaux-des-professionnels-de-la-biodiversite\/"},{"@type":"ListItem","position":2,"name":"Acteurs","item":"https:\/\/a-igeco.fr\/acteurs\/"},{"@type":"ListItem","position":3,"name":"\u00c9cologie fonctionnelle et \u00e9cotoxicologie des agro\u00e9cosyst\u00e8mes EcoSys"}]},{"@type":"WebSite","@id":"https:\/\/a-igeco.fr\/#website","url":"https:\/\/a-igeco.fr\/","name":"A-Igeco","description":"","publisher":{"@id":"https:\/\/a-igeco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a-igeco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/a-igeco.fr\/#organization","name":"A-Igeco","url":"https:\/\/a-igeco.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","contentUrl":"https:\/\/a-igeco.fr\/wp-content\/uploads\/2025\/12\/Logo_A-IGEco_blanc.png","width":1841,"height":678,"caption":"A-Igeco"},"image":{"@id":"https:\/\/a-igeco.fr\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"newspack-article-block-landscape-large":false,"newspack-article-block-portrait-large":false,"newspack-article-block-square-large":false,"newspack-article-block-landscape-medium":false,"newspack-article-block-portrait-medium":false,"newspack-article-block-square-medium":false,"newspack-article-block-landscape-intermediate":false,"newspack-article-block-portrait-intermediate":false,"newspack-article-block-square-intermediate":false,"newspack-article-block-landscape-small":false,"newspack-article-block-portrait-small":false,"newspack-article-block-square-small":false,"newspack-article-block-landscape-tiny":false,"newspack-article-block-portrait-tiny":false,"newspack-article-block-square-tiny":false,"newspack-article-block-uncropped":false},"uagb_author_info":{"display_name":"Zedd Grenoble","author_link":"https:\/\/a-igeco.fr\/en\/author\/zeddgre\/"},"uagb_comment_info":0,"uagb_excerpt":"Les travaux de l\u2019UMR\u00a0visent \u00e0 traiter d\u2019une mani\u00e8re int\u00e9gr\u00e9e le fonctionnement des agro\u00e9cosyst\u00e8mes et leurs relations avec l\u2019environnement. Ce fonctionnement est appr\u00e9hend\u00e9 en particulier \u00e0 partir des concepts de l\u2019\u00e9cologie fonctionnelle et de l\u2019\u00e9cotoxicologie, prenant en compte les flux de mati\u00e8re et d\u2019\u00e9nergie et les fonctions des organismes isol\u00e9s ou en interaction avec leur milieu&hellip;","_links":{"self":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur\/15286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/acteur"}],"about":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/types\/acteur"}],"author":[{"embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"wp:attachment":[{"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/media?parent=15286"}],"wp:term":[{"taxonomy":"type_acteur","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/type_acteur?post=15286"},{"taxonomy":"perimetre_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/perimetre_intervention?post=15286"},{"taxonomy":"milieux_intervention","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/milieux_intervention?post=15286"},{"taxonomy":"domaine_activite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/domaine_activite?post=15286"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/thematique?post=15286"},{"taxonomy":"recherche_umr","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_umr?post=15286"},{"taxonomy":"recherche_centre","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_centre?post=15286"},{"taxonomy":"recherche_universite","embeddable":true,"href":"https:\/\/a-igeco.fr\/en\/wp-json\/wp\/v2\/recherche_universite?post=15286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}